{"id":227,"count":3,"description":"","link":"https:\/\/extende.realisateurweb.com\/fr\/?taxonomy=conference&term=aend","name":"AEND","slug":"aend","taxonomy":"conference","parent":0,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/extende.realisateurweb.com\/fr\/wp-json\/wp\/v2\/conference\/227","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/extende.realisateurweb.com\/fr\/wp-json\/wp\/v2\/conference"}],"about":[{"href":"https:\/\/extende.realisateurweb.com\/fr\/wp-json\/wp\/v2\/taxonomies\/conference"}]}}