{"id":3235,"date":"2025-06-24T18:34:20","date_gmt":"2025-06-24T16:34:20","guid":{"rendered":"https:\/\/extende.realisateurweb.com\/la-simulation-cnd\/documentation\/validation-experimentale-des-modeles-civa\/validation-experimentale-des-modeles-civa-en-ultrasons\/ultrasons-tofd\/ut-tofd-resultats-sur-les-bords-bas-dentailles\/"},"modified":"2025-07-24T11:12:03","modified_gmt":"2025-07-24T09:12:03","slug":"ut-tofd-resultats-sur-les-bords-bas-dentailles","status":"publish","type":"page","link":"https:\/\/extende.realisateurweb.com\/fr\/la-simulation-cnd\/documentation\/validation-experimentale-des-modeles-civa\/validation-experimentale-des-modeles-civa-en-ultrasons\/ultrasons-tofd\/ut-tofd-resultats-sur-les-bords-bas-dentailles\/","title":{"rendered":"UT &#8211; TOFD : R\u00e9sultats sur les bords bas d&rsquo;entailles"},"content":{"rendered":"<p class=\"titre-accordeon\">\u00a0<\/p>\n<p>&nbsp;<\/p>\n<h2 class=\"titre-accordeon\">Configurations exp\u00e9rimentales et de simulation<\/h2>\n<p>&nbsp;<\/p>\n<p class=\"titre-accordeon\">\u00a0<\/p>\n<p>&nbsp;<\/p>\n<h2 class=\"titre-paragraphe\">Proc\u00e9dure exp\u00e9rimentale<\/h2>\n<p>&nbsp;<\/p>\n<p>La maquette utilis\u00e9e (figure ci-dessous) est parall\u00e9l\u00e9pip\u00e9dique, en acier ferritique, de hauteur 30mm. Elle contient 4 d\u00e9fauts plans verticaux d\u2019extension 15mm, d\u2019ouverture 0.2mm et dont la hauteur varie de 7.5mm \u00e0 15mm.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"208\" class=\"alignnone wp-image-3141\" src=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/TOFD_piece_bords_bas.png\" alt=\"\" srcset=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/TOFD_piece_bords_bas.png 550w, https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/TOFD_piece_bords_bas-300x113.png 300w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/>\u00a0<\/p>\n<p>&nbsp;<\/p>\n<p>Les acquisitions en configuration TOFD ont \u00e9t\u00e9 r\u00e9alis\u00e9es avec des capteurs contact de diam\u00e8tre 6.35mm, de fr\u00e9quence centrale 5MHz, g\u00e9n\u00e9rant dans la pi\u00e8ce des ondes longitudinales \u00e0 45\u00b0,60\u00b0 et\u00a0 70\u00b0.<\/p>\n<p>&nbsp;<\/p>\n<p>Pour chaque couple de capteurs (L45\u00b0, L60\u00b0 et L70\u00b0), l\u2019\u00e9cho de diffraction L du bord bas des 4 entailles de hauteurs 15mm, 12.5mm, 10mm et 7.5mm a \u00e9t\u00e9 mesur\u00e9 avec une PCS augmentant lentement de sorte que les deux param\u00e8tres suivants varient lentement:<\/p>\n<p>&nbsp;<\/p>\n<ul class=\"liste-carres-noirs\" style=\"margin-left: 40px;\">\n<li><strong>la distance \u00ab |D| \u00bb<\/strong>, entre le point de croisement des axes des capteurs \u00e0 l\u2019aplomb de l\u2019entaille et le bord bas de l\u2019entaille (Figure ci-dessous). (Nb : \u00ab D \u00bb peut \u00eatre n\u00e9gative)<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"242\" class=\"alignnone wp-image-3142\" src=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/TOFD_distance-D.png\" alt=\"\" srcset=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/TOFD_distance-D.png 500w, https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/TOFD_distance-D-300x145.png 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/p>\n<p>&nbsp;<\/p>\n<ul class=\"liste-carres-noirs\" style=\"margin-left: 40px;\">\n<li><strong>l\u2019angle d\u2019incidence \u03b8<\/strong> des ondes L sur le bord bas de l\u2019entaille (Figure ci-dessous)<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" width=\"328\" height=\"192\" class=\"alignnone wp-image-3143\" src=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/TOFD_angle-teta.png\" alt=\"\" srcset=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/TOFD_angle-teta.png 328w, https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/TOFD_angle-teta-300x176.png 300w\" sizes=\"auto, (max-width: 328px) 100vw, 328px\" \/><\/p>\n<p>&nbsp;<\/p>\n<h2 class=\"titre-paragraphe\">IncertitudeS de mesure<\/h2>\n<p>&nbsp;<\/p>\n<p>Voir le chapitre \u00ab\u00a0Incertitudes\u00a0\u00bb ici : <a class=\"lien\" title=\"(Nouvelle fen\u00eatre)\" href=\"https:\/\/extende.realisateurweb.com\/fr\/la-simulation-cnd\/documentation\/validation-experimentale-des-modeles-civa\/validation-experimentale-des-modeles-civa-en-ultrasons\/ultrasons-tofd\/ut-tofd-presentation-des-configurations-etudiees\/\" target=\"_blank\" rel=\"noopener\">Incertitudes<\/a><\/p>\n<p>&nbsp;<\/p>\n<h2 class=\"titre-paragraphe\">Param\u00e8tres en simulation<\/h2>\n<p>&nbsp;<\/p>\n<p>Se r\u00e9f\u00e9rer au \u00e0 la page <a class=\"lien\" title=\"(Nouvelle fen\u00eatre)\" href=\"https:\/\/extende.realisateurweb.com\/fr\/la-simulation-cnd\/documentation\/validation-experimentale-des-modeles-civa\/validation-experimentale-des-modeles-civa-en-ultrasons\/ultrasons-tofd\/ut-tofd-presentation-des-configurations-etudiees\/\" target=\"_blank\" rel=\"noopener\">\u00ab\u00a0Pr\u00e9sentation des configurations \u00e9tudi\u00e9es\u00a0\u00bb<\/a><\/p>\n<p>&nbsp;<\/p>\n<h2 class=\"titre-paragraphe\">Amplitude de r\u00e9f\u00e9rence<\/h2>\n<p>&nbsp;<\/p>\n<p>La m\u00e9thode employ\u00e9e pour mesurer l&rsquo;amplitude de r\u00e9f\u00e9rence est d\u00e9crite dans le chapitre \u00ab\u00a0comparaison d&rsquo;amplitude et temps de vol\u00a0\u00bb ici : <a class=\"lien\" title=\"(Nouvelle fen\u00eatre)\" href=\"https:\/\/extende.realisateurweb.com\/fr\/la-simulation-cnd\/documentation\/validation-experimentale-des-modeles-civa\/validation-experimentale-des-modeles-civa-en-ultrasons\/ultrasons-tofd\/ut-tofd-presentation-des-configurations-etudiees\/\" target=\"_blank\" rel=\"noopener\">Amplitude de r\u00e9f\u00e9rence<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Pour chaque couple de capteurs (L45\u00b0, L60\u00b0 et L70\u00b0) les amplitudes maximales des \u00e9chos de diffraction du bord bas d\u2019une entaille de hauteur donn\u00e9e seront trac\u00e9es en fonction:<\/p>\n<p>&nbsp;<\/p>\n<ul class=\"liste-carres-noirs\" style=\"margin-left: 40px;\">\n<li>de la PCS. Un trait bleu en pointill\u00e9 indiquera la PCS pour laquelle la profondeur du point de croisement des axes L et du bord bas de l\u2019entaille sont les m\u00eames.<\/li>\n<li>de l\u2019angle d\u2019incidence \u03b8 des ondes L sur le bord bas<\/li>\n<li>de la distance \u00ab D \u00bb entre le point de croisement des axes des capteurs \u00e0 l\u2019aplomb de l\u2019entaille et le bord bas de l\u2019entaille<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p class=\"titre-accordeon\">\u00a0<\/p>\n<p>&nbsp;<\/p>\n<h2 class=\"titre-accordeon\">Comparaison des amplitudes Simulation vs Exp\u00e9rience<\/h2>\n<p>&nbsp;<\/p>\n<p>Ici nous pr\u00e9sentons les courbes de comparaisons des amplitudes des \u00e9chos de diffraction des bords bas des entailles mesur\u00e9es et pr\u00e9dites avec CIVA GTD, CIVA GTD MV et CIVA ATHENA 2D.<\/p>\n<p>&nbsp;<\/p>\n<h2 class=\"titre-paragraphe\">Capteurs L45\u00b0<\/h2>\n<p>&nbsp;<\/p>\n<p>D\u2019apr\u00e8s les mesures, l\u2019angle de r\u00e9fraction des ondes L \u00e9mises par chacun des deux capteurs dans la pi\u00e8ce est 44.5\u00b0. L\u2019amplitude de r\u00e9f\u00e9rence correspond \u00e0 l\u2019amplitude maximum de l\u2019\u00e9cho direct L d\u2019un trou\u00a0 g\u00e9n\u00e9ratrice de diam\u00e8tre 2 mm situ\u00e9 \u00e0 20mm de profondeur lorsque la PCS est de 38mm.<\/p>\n<p>&nbsp;<\/p>\n<p>Les 4 entailles et les axes L des capteurs pour diff\u00e9rentes PCS sont repr\u00e9sent\u00e9s sur la figure ci-dessous afin de visualiser les profondeurs des points de croisement des axes et celles des bords bas des entailles.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"208\" class=\"alignnone wp-image-3144\" src=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_1.png\" alt=\"\" srcset=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_1.png 600w, https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_1-300x104.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>&nbsp;<\/p>\n<h3 class=\"titre-paragraphe\">R\u00e9sultats pour l\u2019entaille de hauteur 15mm<\/h3>\n<p>&nbsp;<\/p>\n<p>Les r\u00e9sultats exp\u00e9rimentaux et de simulation pour l\u2019entaille de 15mm de hauteur sont pr\u00e9sent\u00e9s sur la figure ci-dessous.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"279\" class=\"alignnone wp-image-3145\" src=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_2.png\" alt=\"\" srcset=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_2.png 600w, https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_2-300x140.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>La comparaison de la courbe exp\u00e9rimentale (en noir) avec la courbe simul\u00e9e avec CIVA_GTD (en rouge) montre que les amplitudes simul\u00e9es sont toujours plus faibles que celles mesur\u00e9es. L\u2019\u00e9cart le plus important (24 dB) est mesur\u00e9 pour la PCS la plus faible (23mm).<\/p>\n<p>&nbsp;<\/p>\n<p>La comparaison des r\u00e9sultats de simulation CIVA_GTD et CIVA_GTD_MV montre que les deux mod\u00e8les donnent des r\u00e9sultats proches lorsque la distance |D| entre la profondeur du bord bas et le point de croisement\u00a0 est comprise entre -1 mm et 6.5 mm. Au-del\u00e0 de cet intervalle, les \u00e9carts en\u00a0 amplitude entre les 2 mod\u00e8les d\u00e9passent 3 dB. Ce r\u00e9sultat est en accord avec l\u2019approximation du champ dans CIVA lors du calcul de l\u2019interaction du champ incident et de l\u2019entaille (voir plus loin). Les \u00e9carts entre CIVA_GTD et CIVA_GTD_MV n\u2019apparaissent que lorsque |D| augmente, c\u2019est-\u00e0-dire lorsque la description approch\u00e9e du champ n\u2019est plus valide.<\/p>\n<p>&nbsp;<\/p>\n<p>On remarque \u00e9galement que les amplitudes obtenues avec CIVA_GTD_MV sont tr\u00e8s proches des amplitudes exp\u00e9rimentales lorsque les angles d\u2019incidence \u03b8 sont sup\u00e9rieurs \u00e0 51.5\u00b0. Pour les autres angles d\u2019incidence, les amplitudes simul\u00e9es sont inf\u00e9rieures aux amplitudes mesur\u00e9es.<\/p>\n<p>&nbsp;<\/p>\n<p>Les r\u00e9sultats de simulations CIVA_ATHENA_2D sont illustr\u00e9s ci-dessous. Ils permettent de comparer l\u2019effet de l\u2019ouverture de l\u2019entaille sur les amplitudes de bord bas.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" width=\"560\" height=\"292\" class=\"alignnone wp-image-3146\" src=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_3.png\" alt=\"\" srcset=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_3.png 560w, https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_3-300x156.png 300w\" sizes=\"auto, (max-width: 560px) 100vw, 560px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>On peut voir que pour des angles d\u2019incidence \u03b8 inf\u00e9rieurs \u00e0 51.5\u00b0, les amplitudes des \u00e9chos obtenues avec CIVA_ATHENA_2D pour les entailles d\u2019ouverture 0.2mm sont sup\u00e9rieures \u00e0 celles des entailles d\u2019ouverture quasi-nulle. Etant donn\u00e9 que pour ces angles CIVA_GTD_MV sous-estime les amplitudes par rapport \u00e0 la mesure, la prise en compte de l\u2019ouverture r\u00e9elle des entailles en \u00ab 3D \u00bb r\u00e9duirait certainement cette sous-estimation.<\/p>\n<p>&nbsp;<\/p>\n<p>Pour les angles d\u2019incidence \u03b8 sup\u00e9rieurs \u00e0 51.5\u00b0, la prise en compte de l\u2019ouverture de l\u2019entaille ne modifie significativement pas les r\u00e9sultats. Les amplitudes sont tr\u00e8s proches. Pour ces angles d\u2019incidence, la prise en compte de l\u2019ouverture r\u00e9elle des entailles ne modifierait pas le bon accord observ\u00e9 entre CIVA_GTD_MV et l\u2019exp\u00e9rience.<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #1189bb; font-size: 1em; font-weight: bolder; line-height: 1.5em;\">R\u00e9sultats pour l\u2019entaille de hauteur 12.5 mm<\/span><\/p>\n<p>&nbsp;<\/p>\n<p>Les r\u00e9sultats exp\u00e9rimentaux et de simulation avec l\u2019entaille de 12.5mm de hauteur sont pr\u00e9sent\u00e9s sur la figure ci-dessous.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"273\" class=\"alignnone wp-image-3147\" src=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_4.png\" alt=\"\" srcset=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_4.png 600w, https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_4-300x137.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>La comparaison de la courbe exp\u00e9rimentale (en noir) avec la courbe simul\u00e9e avec CIVA_GTD (en rouge) montre que les amplitudes simul\u00e9es sont plus faibles que les exp\u00e9rimentales. L\u2019\u00e9cart le plus important (15 dB) est mesur\u00e9 pour la PCS la plus faible (23mm).<\/p>\n<p>&nbsp;<\/p>\n<p>La comparaison des r\u00e9sultats de simulation CIVA_GTD et CIVA_GTD_MV montre que les deux mod\u00e8les donnent des r\u00e9sultats proches (\u00e9carts inf\u00e9rieurs \u00e0 3dB) \u00a0lorsque la distance |D| entre la profondeur du bord bas et le point de croisement\u00a0 est inf\u00e9rieure \u00e0 5 mm. Ce r\u00e9sultat est en accord avec l\u2019approximation du champ dans CIVA (voir plus loin). Les \u00e9carts entre CIVA_GTD et CIVA_GTD_MV n\u2019apparaissent que lorsque |D| augmente, c\u2019est-\u00e0-dire lorsque la description approch\u00e9e du champ n\u2019est plus valide.<\/p>\n<p>&nbsp;<\/p>\n<p>On remarque \u00e9galement que les amplitudes obtenues avec CIVA_GTD_MV\u00a0 sont tr\u00e8s proches des amplitudes exp\u00e9rimentales pour des angles d\u2019incidence \u03b8 sup\u00e9rieurs \u00e0 53\u00b0. Pour les autres angles d\u2019incidence, les amplitudes simul\u00e9es sont inf\u00e9rieures aux amplitudes mesur\u00e9es.<\/p>\n<p>&nbsp;<\/p>\n<p>Les r\u00e9sultats de simulations CIVA_ATHENA_2D sont pr\u00e9sent\u00e9s ci-dessous. Ils permettent de comparer l\u2019effet de l\u2019ouverture de l\u2019entaille sur les amplitudes de bord bas.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" width=\"564\" height=\"291\" class=\"alignnone wp-image-3148\" src=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_5.png\" alt=\"\" srcset=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_5.png 564w, https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_5-300x155.png 300w\" sizes=\"auto, (max-width: 564px) 100vw, 564px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>On peut voir que pour des angles d\u2019incidence \u03b8 inf\u00e9rieurs \u00e0 53\u00b0, les amplitudes des \u00e9chos simul\u00e9s avec CIVA_ATHENA_2D pour les entailles d\u2019ouverture 0.2mm sont sup\u00e9rieures \u00e0 celles des entailles d\u2019ouverture quasi-nulle. Etant donn\u00e9 que pour ces angles CIVA_GTD_MV sous-estime les amplitudes par rapport \u00e0 la mesure, la prise en compte de l\u2019ouverture r\u00e9elle des entailles en \u00ab 3D \u00bb r\u00e9duirait certainement cette sous-estimation.<\/p>\n<p>&nbsp;<\/p>\n<p>Pour des angles d\u2019incidence \u03b8 sup\u00e9rieurs \u00e0 53\u00b0, les amplitudes obtenues pour les entailles ouvertes et d\u2019ouverture quasi-nulle sont tr\u00e8s proches. Prendre en compte l\u2019ouverture r\u00e9elle des entailles ne modifierait donc pas le bon accord entre CIVA_GTD_MV et l\u2019exp\u00e9rience.<\/p>\n<p>&nbsp;<\/p>\n<h3 class=\"titre-paragraphe\">R\u00e9sultats pour l\u2019entaille de hauteur 10 mm<\/h3>\n<p>&nbsp;<\/p>\n<p>Les r\u00e9sultats exp\u00e9rimentaux et de simulation avec l\u2019entaille de 10 mm de hauteur sont pr\u00e9sent\u00e9s sur la figure ci-dessous.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"278\" class=\"alignnone wp-image-3149\" src=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_6.png\" alt=\"\" srcset=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_6.png 600w, https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_6-300x139.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>La comparaison de la courbe exp\u00e9rimentale (en noir) avec la courbe simul\u00e9e avec CIVA_GTD (en rouge) montre que les amplitudes simul\u00e9es sont plus faibles que les exp\u00e9rimentales. L\u2019\u00e9cart le plus important (12 dB) est mesur\u00e9 pour la PCS la plus forte (53mm).<\/p>\n<p>&nbsp;<\/p>\n<p>La comparaison des r\u00e9sultats de simulation CIVA_GTD et CIVA_GTD_MV montre que les deux mod\u00e8les donnent des r\u00e9sultats proches (\u00e9carts inf\u00e9rieurs \u00e0 3dB)\u00a0 lorsque la distance |D| entre la profondeur du bord bas et le point de croisement\u00a0 est inf\u00e9rieure \u00e0 4 mm. Ce r\u00e9sultat est en accord avec l\u2019approximation du champ dans CIVA (voir plus loin). Les \u00e9carts entre CIVA_GTD et CIVA_GTD_MV n\u2019apparaissent que lorsque |D| augmente, c\u2019est-\u00e0-dire lorsque la description approch\u00e9e du champ n\u2019est plus valide.<\/p>\n<p>&nbsp;<\/p>\n<p>On remarque \u00e9galement que les amplitudes obtenues avec CIVA_GTD_MV\u00a0 sont tr\u00e8s proches des amplitudes exp\u00e9rimentales pour des angles d\u2019incidence \u03b8 sup\u00e9rieurs \u00e0 53\u00b0. Pour les autres angles d\u2019incidence, les amplitudes simul\u00e9es sont inf\u00e9rieures aux amplitudes mesur\u00e9es.<\/p>\n<p>&nbsp;<\/p>\n<p>Les r\u00e9sultats de simulations CIVA_ATHENA_2D (ci-dessous) permettent de comparer l\u2019effet de l\u2019ouverture de l\u2019entaille sur les amplitudes de bord bas.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" width=\"556\" height=\"298\" class=\"alignnone wp-image-3150\" src=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_7.png\" alt=\"\" srcset=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_7.png 556w, https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_7-300x161.png 300w\" sizes=\"auto, (max-width: 556px) 100vw, 556px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>On peut voir que pour des angles d\u2019incidence \u03b8 inf\u00e9rieurs \u00e0 50\u00b0, les amplitudes des \u00e9chos obtenues avec CIVA_ATHENA_2D pour les entailles d\u2019ouverture 0.2mm sont sup\u00e9rieures \u00e0 celles des entailles d\u2019ouverture quasi-nulle. Etant donn\u00e9 que pour ces angles CIVA_GTD_MV sous-estime les amplitudes par rapport \u00e0 la mesure, la prise en compte de l\u2019ouverture r\u00e9elle des entailles en \u00ab 3D \u00bb r\u00e9duirait probablement cette sous-estimation.<\/p>\n<p>&nbsp;<\/p>\n<p>Pour des angles d\u2019incidence \u03b8 sup\u00e9rieurs \u00e0 50\u00b0, les amplitudes obtenues pour les entailles ouvertes et d\u2019ouverture quasi-nulle sont tr\u00e8s proches. Par ailleurs, prendre en compte l\u2019ouverture r\u00e9elle des entailles ne modifierait pas le bon accord entre CIVA_GTD_MV et l\u2019exp\u00e9rience.<\/p>\n<p>&nbsp;<\/p>\n<h3 class=\"titre-paragraphe\">R\u00e9sultats pour l\u2019entaille de hauteur 7.5 mm<\/h3>\n<p>&nbsp;<\/p>\n<p>Les r\u00e9sultats exp\u00e9rimentaux et de simulation avec l\u2019entaille de 7.5 mm de hauteur sont pr\u00e9sent\u00e9s sur la figure ci-dessous.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"289\" class=\"alignnone wp-image-3151\" src=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_8.png\" alt=\"\" srcset=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_8.png 600w, https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_8-300x145.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>La comparaison de la courbe exp\u00e9rimentale (en noir) avec la courbe simul\u00e9e avec CIVA_GTD (en rouge) montre que les amplitudes simul\u00e9es sont plus faibles les amplitudes exp\u00e9rimentales. L\u2019\u00e9cart le plus important (14 dB) est mesur\u00e9 pour la PCS la plus forte (53mm).<\/p>\n<p>&nbsp;<\/p>\n<p>La comparaison des r\u00e9sultats de simulation CIVA_GTD et CIVA_GTD_MV montre que les amplitudes mesur\u00e9es avec CIVA_GTD_MV sont toujours sup\u00e9rieures \u00e0 celles obtenues avec CIVA_GTD d\u00e8s lors que |D| est sup\u00e9rieure \u00e0 4 mm.<\/p>\n<p>&nbsp;<\/p>\n<p>On remarque \u00e9galement que les amplitudes obtenues avec CIVA_GTD_MV sont tr\u00e8s proches des amplitudes exp\u00e9rimentales pour des angles d\u2019incidence \u03b8 sup\u00e9rieurs \u00e0 57\u00b0.\u00a0<\/p>\n<p>&nbsp;<\/p>\n<h3 class=\"titre-paragraphe\">Conclusion sur la d\u00e9tection en L45\u00b0<\/h3>\n<p>&nbsp;<\/p>\n<p>Afin d\u2019obtenir des r\u00e9sultats de simulation avec le mod\u00e8le GTD proches des r\u00e9sultats exp\u00e9rimentaux, il faut soit utiliser une description du champ plus pr\u00e9cise et\/ou prendre en compte l\u2019ouverture de l\u2019entaille par le biais d\u2019une simulation CIVA\u00a0 ATHENA 2D.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h2 class=\"titre-paragraphe\">Capteurs L60\u00b0<\/h2>\n<p>&nbsp;<\/p>\n<p>D\u2019apr\u00e8s les mesures exp\u00e9rimentales, l\u2019angle de r\u00e9fraction des ondes L \u00e9mises par chacun des deux capteurs dans la pi\u00e8ce est 59\u00b0. L\u2019amplitude de r\u00e9f\u00e9rence choisie est l\u2019amplitude maximum de l\u2019\u00e9cho direct L d\u2019un trou\u00a0 g\u00e9n\u00e9ratrice de diam\u00e8tre 2 mm situ\u00e9 \u00e0 20mm de profondeur obtenue lorsque la PCS est de 68mm.<\/p>\n<p>&nbsp;<\/p>\n<p>Les 4 entailles et les axes L des capteurs pour diff\u00e9rentes PCS sont repr\u00e9sent\u00e9s sur la figure ci-dessous pour diff\u00e9rentes PCS.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"196\" class=\"alignnone wp-image-3152\" src=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_9.png\" alt=\"\" srcset=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_9.png 600w, https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_9-300x98.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>&nbsp;<\/p>\n<h3 class=\"titre-paragraphe\">R\u00e9sultats pour l\u2019entaille de hauteur 15mm<\/h3>\n<p>&nbsp;<\/p>\n<p>Les r\u00e9sultats exp\u00e9rimentaux et de simulation avec l\u2019entaille de 15mm de hauteur sont pr\u00e9sent\u00e9s sur la figure ci-dessous.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"312\" class=\"alignnone wp-image-3153\" src=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_10.png\" alt=\"\" srcset=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_10.png 600w, https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_10-300x156.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>La comparaison de la courbe exp\u00e9rimentale (en noir) avec la courbe simul\u00e9e avec CIVA_GTD (en rouge) montre que les amplitudes simul\u00e9es sont toujours plus faibles que celles mesur\u00e9es. La sous-estimation est constante et \u00e9gale \u00e0 3 \u00e0 4 dB environ.<\/p>\n<p>&nbsp;<\/p>\n<p>Par ailleurs, on v\u00e9rifie que l\u2019amplitude maximale est mesur\u00e9e lorsque la PCS est la plus proche de la PCS de r\u00e9f\u00e9rence pour laquelle les axes L des capteurs se croisent au niveau du bord bas (symbolis\u00e9e par le trait vertical en pointill\u00e9 bleu).<\/p>\n<p>&nbsp;<\/p>\n<p>La comparaison des r\u00e9sultats de simulation CIVA_GTD et CIVA_GTD_MV montre que les deux mod\u00e8les donnent des r\u00e9sultats assez proches quelle que soit la distance |D| entre la profondeur du bord bas et le point de croisement.\u00a0<\/p>\n<p>&nbsp;<\/p>\n<p>Les r\u00e9sultats de simulations CIVA_ATHENA 2D ci-dessous permettent de comparer l\u2019effet de l\u2019ouverture de l\u2019entaille sur les amplitudes de bord bas.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"321\" class=\"alignnone wp-image-3154\" src=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_11.png\" alt=\"\" srcset=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_11.png 600w, https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_11-300x161.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>La prise en compte de l\u2019ouverture de l\u2019entaille permet de mesurer des amplitudes d\u2019\u00e9chos de diffraction plus \u00e9lev\u00e9es en particulier pour les angles d\u2019incidence \u03b8 inf\u00e9rieurs \u00e0 60.5\u00b0.\u00a0 Il semble donc possible de r\u00e9duire l\u2019\u00e9cart entre la simulation avec CIVA_GTD_MV (pour les angles d\u2019incidence inf\u00e9rieurs \u00e0 62\u00b0) en prenant en compte l\u2019ouverture de l\u2019entaille. Cependant, un tel mod\u00e8le \u00ab\u00a03D\u00a0\u00bb n\u2019est pas encore disponible. Par ailleurs, pour les angles d\u2019incidence sup\u00e9rieurs \u00e0 60.5\u00b0, on conserverait la sous-estimation de 2 \u00e0 3 dB de l\u2019amplitude de diffraction par CIVA_GTD_MV, ce qui reste acceptable compte tenu de l\u2019incertitude de mesure.<\/p>\n<p>&nbsp;<\/p>\n<h3 class=\"titre-paragraphe\">R\u00e9sultats pour l\u2019entaille de hauteur 12.5 mm<\/h3>\n<p>&nbsp;<\/p>\n<p>Les r\u00e9sultats exp\u00e9rimentaux et de simulation avec l\u2019entaille de 12.5mm de hauteur sont pr\u00e9sent\u00e9s sur la figure ci-dessous.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"303\" class=\"alignnone wp-image-3155\" src=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_12.png\" alt=\"\" srcset=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_12.png 600w, https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_12-300x152.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>La comparaison de la courbe exp\u00e9rimentale (en noir) avec la courbe simul\u00e9e CIVA_GTD (en rouge) montre que les amplitudes simul\u00e9es sont toujours plus faibles que celles mesur\u00e9es. La sous-estimation est constante et \u00e9gale \u00e0 3 \u00e0 4 dB environ.<\/p>\n<p>&nbsp;<\/p>\n<p>Par ailleurs, on v\u00e9rifie que l\u2019amplitude maximale est mesur\u00e9e lorsque la PCS est la plus proche de la PCS de r\u00e9f\u00e9rence symbolis\u00e9e par le trait vertical bleu en pointill\u00e9.<\/p>\n<p>&nbsp;<\/p>\n<p>La comparaison des r\u00e9sultats de simulation CIVA_GTD et CIVA_GTD_MV montre que les deux mod\u00e8les donnent des r\u00e9sultats assez proches quelle que soit la distance |D| entre la profondeur du bord bas et le point de croisement.\u00a0<\/p>\n<p>&nbsp;<\/p>\n<p>Les r\u00e9sultats de simulations CIVA_ATHENA_2D (ci-dessous) permettent de comparer l\u2019effet de l\u2019ouverture de l\u2019entaille sur les amplitudes de bord bas.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"308\" class=\"alignnone wp-image-3156\" src=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_13.png\" alt=\"\" srcset=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_13.png 600w, https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_13-300x154.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>La prise en compte de l\u2019ouverture de l\u2019entaille permet de mesurer des amplitudes d\u2019\u00e9chos de diffraction plus \u00e9lev\u00e9s, en particulier pour les angles d\u2019incidence \u03b8 inf\u00e9rieurs \u00e0 60\u00b0.\u00a0 Il semble donc possible de r\u00e9duire l\u2019\u00e9cart entre la simulation avec CIVA_GTD_MV (pour les angles d\u2019incidence inf\u00e9rieurs \u00e0 60\u00b0) en prenant en compte l\u2019ouverture de l\u2019entaille. Cependant, un tel mod\u00e8le \u00ab\u00a03D\u00a0\u00bb n\u2019est pas encore disponible. N\u00e9anmoins, pour les angles d\u2019incidence sup\u00e9rieurs \u00e0 60\u00b0, on conserverait la sous-estimation de 2 \u00e0 3 dB de l\u2019amplitude de diffraction par CIVA_GTD_MV. \u00a0Cela reste acceptable compte tenu de l\u2019incertitude de mesure.<\/p>\n<p>&nbsp;<\/p>\n<h3 class=\"titre-paragraphe\">R\u00e9sultats pour l\u2019entaille de hauteur 10 mm<\/h3>\n<p>&nbsp;<\/p>\n<p>Les r\u00e9sultats exp\u00e9rimentaux et de simulation avec l\u2019entaille de 10mm de hauteur sont pr\u00e9sent\u00e9s sur la figure ci-dessous.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"307\" class=\"alignnone wp-image-3157\" src=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_14.png\" alt=\"\" srcset=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_14.png 600w, https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_14-300x154.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>La comparaison de la courbe exp\u00e9rimentale (en noir) avec la courbe simul\u00e9e CIVA_GTD (en rouge) montre que les amplitudes simul\u00e9es sont toujours plus faibles que les amplitudes exp\u00e9rimentales. La sous-estimation augmente avec la PCS\u00a0: elle est d\u2019environ 3 \u00e0 4 dB pour les petites PCS et 6 \u00e0 7 dB pour les plus grandes.<\/p>\n<p>&nbsp;<\/p>\n<p>Par ailleurs, on v\u00e9rifie que l\u2019amplitude maximale est mesur\u00e9e lorsque la PCS est la plus proche de la PCS de r\u00e9f\u00e9rence (\u00e0 l\u2019endroit du trait bleu en pointill\u00e9) pour laquelle les axes L des capteurs se croisent au niveau du bord bas.<\/p>\n<p>&nbsp;<\/p>\n<p>La comparaison des r\u00e9sultats de simulation CIVA_GTD et CIVA_GTD_MV montre que les deux mod\u00e8les donnent des r\u00e9sultats assez proches jusqu\u2019\u00e0 ce que la distance |D| soit \u00e9gale \u00e0 8mm. Au-del\u00e0, les amplitudes CIVA_GTD_MV sont sup\u00e9rieures \u00e0 celles obtenues avec CIVA_GTD.<\/p>\n<p>&nbsp;<\/p>\n<p>Les r\u00e9sultats de simulations CIVA_ATHENA_2D (ci-dessous) permettent de comparer l\u2019effet de l\u2019ouverture de l\u2019entaille sur les amplitudes de bord bas.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"318\" class=\"alignnone wp-image-3158\" src=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_15.png\" alt=\"\" srcset=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_15.png 600w, https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_15-300x159.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>La prise en compte de l\u2019ouverture de l\u2019entaille permet d\u2019obtenir des amplitudes d\u2019\u00e9chos de diffraction plus \u00e9lev\u00e9es en particulier pour les angles d\u2019incidence \u03b8 inf\u00e9rieurs \u00e0 62\u00b0.\u00a0 Il semble donc possible de r\u00e9duire l\u2019\u00e9cart entre la simulation avec CIVA_GTD_MV (pour les angles d\u2019incidence inf\u00e9rieurs \u00e0 62\u00b0) en prenant en compte l\u2019ouverture de l\u2019entaille. Cependant, un tel mod\u00e8le \u00ab\u00a03D\u00a0\u00bb n\u2019est pas encore disponible. Par ailleurs, pour les angles d\u2019incidence sup\u00e9rieurs \u00e0 62\u00b0, on conserverait la sous-estimation de 2 \u00e0 3 dB de l\u2019amplitude de diffraction par CIVA_GTD_MV, ce qui reste acceptable compte tenu de l\u2019incertitude de mesure.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h3 class=\"titre-paragraphe\">R\u00e9sultats pour l\u2019entaille de hauteur 7.5 mm<\/h3>\n<p>&nbsp;<\/p>\n<p>Les r\u00e9sultats exp\u00e9rimentaux et de simulation avec l\u2019entaille de 7.5mm de hauteur sont pr\u00e9sent\u00e9s sur la figure ci-dessous.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"309\" class=\"alignnone wp-image-3159\" src=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_16.png\" alt=\"\" srcset=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_16.png 600w, https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_16-300x155.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>La comparaison de la courbe exp\u00e9rimentale (en noir) avec la courbe simul\u00e9e CIVA_GTD (en rouge) montre que les amplitudes simul\u00e9es sont toujours plus faibles que les amplitudes exp\u00e9rimentales. La sous-estimation augmente avec la PCS\u00a0: elle est d\u2019environ 3 \u00e0 4 dB pour les petites PCS et 6 \u00e0 7 dB pour les plus grandes (7 dB \u00e0 la PCS de 78mm).<\/p>\n<p>&nbsp;<\/p>\n<p>La comparaison des r\u00e9sultats de simulation CIVA_GTD et CIVA_GTD_MV montre que les deux mod\u00e8les diff\u00e8rent significativement d\u00e8s que la distance |D| est \u00e9gale \u00e0 6 mm. Au-del\u00e0 de cette distance, les amplitudes CIVA_GTD_MV sont sup\u00e9rieures \u00e0 celles obtenues avec CIVA_GTD.<\/p>\n<p>&nbsp;<\/p>\n<h3 class=\"titre-paragraphe\">Conclusion sur la d\u00e9tection en L60\u00b0<\/h3>\n<p>&nbsp;<\/p>\n<p>Afin d\u2019obtenir des r\u00e9sultats de simulation avec le mod\u00e8le GTD proches des r\u00e9sultats exp\u00e9rimentaux, il faut soit utiliser une description du champ plus pr\u00e9cise et\/ou prendre en compte l\u2019ouverture de l\u2019entaille par le biais d\u2019une simulation CIVA_ATHENA_2D.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h2 class=\"titre-paragraphe\">Capteurs L70\u00b0<\/h2>\n<p>&nbsp;<\/p>\n<p>D\u2019apr\u00e8s les mesures, l\u2019angle de r\u00e9fraction des ondes L \u00e9mises par chacun des deux capteurs dans la pi\u00e8ce est 70\u00b0. L\u2019amplitude de r\u00e9f\u00e9rence choisie est l\u2019amplitude maximum de l\u2019\u00e9cho direct L d\u2019un trou\u00a0 g\u00e9n\u00e9ratrice de diam\u00e8tre 0.7 mm situ\u00e9 \u00e0 10 mm de profondeur obtenue lorsque la PCS est de 53mm.<\/p>\n<p>&nbsp;<\/p>\n<p>Les 4 entailles et les axes L des capteurs pour diff\u00e9rentes PCS sont repr\u00e9sent\u00e9s sur la figure ci-dessous.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"156\" class=\"alignnone wp-image-3160\" src=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_17.png\" alt=\"\" srcset=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_17.png 600w, https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_17-300x78.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>&nbsp;<\/p>\n<h3 class=\"titre-paragraphe\">R\u00e9sultats pour l\u2019entaille de hauteur 15mm<\/h3>\n<p>&nbsp;<\/p>\n<p>Les r\u00e9sultats exp\u00e9rimentaux et de simulation avec l\u2019entaille de 15mm de hauteur sont pr\u00e9sent\u00e9s sur la figure ci-dessous.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"266\" class=\"alignnone wp-image-3161\" src=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_18.png\" alt=\"\" srcset=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_18.png 600w, https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_18-300x133.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>La comparaison de la courbe exp\u00e9rimentale (en noir) avec la courbe simul\u00e9e avec CIVA_GTD (en rouge) montre que les amplitudes simul\u00e9es sont proches des amplitudes exp\u00e9rimentales sauf pour les plus petites PCS. Pour ces derni\u00e8res, l\u2019amplitude simul\u00e9e est plus faible que l\u2019amplitude exp\u00e9rimentale.<\/p>\n<p>&nbsp;<\/p>\n<p>La comparaison des r\u00e9sultats de simulation CIVA_GTD et CIVA_GTD_MV montre que les deux mod\u00e8les donnent des r\u00e9sultats assez proches pour les distances |D| entre la profondeur du bord bas et le point de croisement sup\u00e9rieure \u00e0 -7mm. Pour les distances |D| inf\u00e9rieures \u00e0 -7mm, l\u2019amplitude simul\u00e9e avec CIVA_GTD_MV est sup\u00e9rieure \u00e0 celle mesur\u00e9e avec CIVA_GTD et est par cons\u00e9quent plus pr\u00e8s de l\u2019exp\u00e9rimentale.<\/p>\n<p>&nbsp;<\/p>\n<p>Les r\u00e9sultats de simulations CIVA ATHENA 2D sont pr\u00e9sent\u00e9s ci-dessous. Ils permettent de comparer l\u2019effet de l\u2019ouverture de l\u2019entaille sur les amplitudes de bord bas.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"292\" class=\"alignnone wp-image-3162\" src=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_19.png\" alt=\"\" srcset=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_19.png 600w, https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_19-300x146.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>La prise en compte de l\u2019ouverture de l\u2019entaille n\u2019a que tr\u00e8s peu d\u2019influence sur les amplitudes simul\u00e9es. En effet, en L70\u00b0, l\u2019angle d\u2019incidence est plus grand qu\u2019en L45\u00b0 ou L60\u00b0 ce qui d\u00e9favorise l\u2019apparition d\u2019ondes rasantes le long de l\u2019ouverture de l\u2019entaille.<\/p>\n<p>&nbsp;<\/p>\n<h3 class=\"titre-paragraphe\">R\u00e9sultats pour l\u2019entaille de hauteur 12.5 mm<\/h3>\n<p>&nbsp;<\/p>\n<p>Les r\u00e9sultats exp\u00e9rimentaux et de simulation avec l\u2019entaille de 12.5mm de hauteur sont pr\u00e9sent\u00e9s sur la figure ci-dessous.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"258\" class=\"alignnone wp-image-3163\" src=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_20.png\" alt=\"\" srcset=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_20.png 600w, https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_20-300x129.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>La comparaison de la courbe exp\u00e9rimentale (en noir) avec la courbe simul\u00e9e avec CIVA_GTD (en rouge) montre que les amplitudes simul\u00e9es sont proches des amplitudes exp\u00e9rimentales sauf pour les plus petites PCS. Pour ces derni\u00e8res, l\u2019amplitude simul\u00e9e est plus faible que l\u2019amplitude exp\u00e9rimentale.<\/p>\n<p>&nbsp;<\/p>\n<p>La comparaison des r\u00e9sultats de simulation CIVA_GTD et CIVA_GTD_MV montre que les deux mod\u00e8les donnent des r\u00e9sultats assez proches pour les distances |D| sup\u00e9rieure \u00e0 -6mm. Pour les distances |D| inf\u00e9rieures \u00e0 -6mm, l\u2019amplitude simul\u00e9e avec CIVA_GTD_MV est sup\u00e9rieure \u00e0 celle mesur\u00e9e avec CIVA_GTD et est par cons\u00e9quent plus pr\u00e8s de l\u2019exp\u00e9rimentale.<\/p>\n<p>&nbsp;<\/p>\n<p>Les r\u00e9sultats de simulations CIVA ATHENA 2D sont pr\u00e9sent\u00e9s ci-dessous. Ils permettent de comparer l\u2019effet de l\u2019ouverture de l\u2019entaille sur les amplitudes de bord bas.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"282\" class=\"alignnone wp-image-3164\" src=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_21.png\" alt=\"\" srcset=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_21.png 600w, https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_21-300x141.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>La prise en compte de l\u2019ouverture de l\u2019entaille n\u2019a que tr\u00e8s peu d\u2019influence sur les amplitudes simul\u00e9es. En effet, en L70\u00b0, l\u2019angle d\u2019incidence est plus grand qu\u2019en L45\u00b0 ou L60\u00b0 ce qui d\u00e9favorise l\u2019apparition d\u2019ondes rasantes le long de l\u2019ouverture de l\u2019entaille.<\/p>\n<p>&nbsp;<\/p>\n<h3 class=\"titre-paragraphe\">R\u00e9sultats pour l\u2019entaille de hauteur 10 mm<\/h3>\n<p>&nbsp;<\/p>\n<p>Les r\u00e9sultats exp\u00e9rimentaux et de simulation avec l\u2019entaille de 10mm de hauteur sont pr\u00e9sent\u00e9s sur la figure ci-dessous.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"264\" class=\"alignnone wp-image-3165\" src=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_22.png\" alt=\"\" srcset=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_22.png 600w, https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_22-300x132.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>La comparaison de la courbe exp\u00e9rimentale (en noir) avec la courbe simul\u00e9e CIVA_GTD (en rouge) montre que les amplitudes simul\u00e9es sont proches de celles mesur\u00e9es sauf pour les plus petites PCS. Pour ces derni\u00e8res l\u2019amplitude simul\u00e9e est plus faible que l\u2019amplitude exp\u00e9rimentale.<\/p>\n<p>&nbsp;<\/p>\n<p>La comparaison des r\u00e9sultats de simulation CIVA_GTD et CIVA_GTD_MV montre que les deux mod\u00e8les donnent des r\u00e9sultats assez proches pour les distances |D|, entre la profondeur du bord bas et le point de croisement, sup\u00e9rieures \u00e0 -5mm. Pour les distances |D| inf\u00e9rieures \u00e0 -5mm, l\u2019amplitude simul\u00e9e avec CIVA_GTD_MV est sup\u00e9rieure \u00e0 celle mesur\u00e9e avec CIVA_GTD et est par cons\u00e9quent plus pr\u00e8s de l\u2019exp\u00e9rimentale.<\/p>\n<p>&nbsp;<\/p>\n<p>Les r\u00e9sultats de simulations CIVA ATHENA 2D, ci-dessous, permettent de comparer l\u2019effet de l\u2019ouverture de l\u2019entaille sur les amplitudes de bord bas.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"289\" class=\"alignnone wp-image-3166\" src=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_23.png\" alt=\"\" srcset=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_23.png 600w, https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_23-300x145.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>La prise en compte de l\u2019ouverture de l\u2019entaille n\u2019a que tr\u00e8s peu d\u2019influence sur les amplitudes simul\u00e9es. En effet, en L70\u00b0, l\u2019angle d\u2019incidence est plus grand qu\u2019en L45\u00b0 ou L60\u00b0 ce qui d\u00e9favorise l\u2019apparition d\u2019ondes rasantes le long de l\u2019ouverture de l\u2019entaille.<\/p>\n<p>&nbsp;<\/p>\n<h3 class=\"titre-paragraphe\">R\u00e9sultats pour l\u2019entaille de hauteur 7.5 mm<\/h3>\n<p>&nbsp;<\/p>\n<p>Les r\u00e9sultats exp\u00e9rimentaux et de simulation avec l\u2019entaille de 7.5mm de hauteur sont pr\u00e9sent\u00e9s sur la figure ci-dessous.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"263\" class=\"alignnone wp-image-3167\" src=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_24.png\" alt=\"\" srcset=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_24.png 600w, https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_24-300x132.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>La comparaison de la courbe exp\u00e9rimentale (en noir) avec la courbe simul\u00e9e avec CIVA_GTD (en rouge) montre que les amplitudes simul\u00e9es sont tr\u00e8s proches de celles mesur\u00e9es pour toutes les PCS.\u00a0<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h3 class=\"titre-paragraphe\">Conclusion sur la d\u00e9tection en L70\u00b0<\/h3>\n<p>&nbsp;<\/p>\n<p>De mani\u00e8re g\u00e9n\u00e9rale, les r\u00e9sultats de simulation sont en bon accord avec l\u2019exp\u00e9rience en particulier pour les PCS les plus grandes.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h2 class=\"titre-paragraphe\">Conclusion g\u00e9n\u00e9rale sur les comparaisons d\u2019amplitude<\/h2>\n<p>&nbsp;<\/p>\n<p>Finalement, les r\u00e9sultats obtenus montrent que pour toutes les inspections L45\u00b0, L60\u00b0 et L70\u00b0, les amplitudes des \u00e9chos de bord bas des entailles pr\u00e9dites par CIVA sont en assez bon accord avec l\u2019exp\u00e9rience pour la plupart des configurations \u00e9tudi\u00e9es. Pour le constater, 2 m\u00e9thodes ont \u00e9t\u00e9 employ\u00e9es :<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li>En calculant l\u2019\u00e9cho de bord bas d\u2019un d\u00e9faut rectangulaire d\u2019ouverture quasi-nulle avec le mod\u00e8le GTD et un d\u00e9faut rectangulaire<\/li>\n<li>En calculant l\u2019\u00e9cho de bord bas d\u2019une entaille avec des capteurs multi\u00e9l\u00e9ments (\u00e9quivalents aux capteurs mono-\u00e9l\u00e9ment originaux) avec le mod\u00e8le CIVA_GTD_MV afin d\u2019utiliser une description plus pr\u00e9cise du champ incident sur le bord et l\u2019ouverture de l\u2019entaille. Cependant, il est \u00e0 noter que ce calcul n\u2019est pas r\u00e9alisable avec CIVA11.0a pour un utilisateur qui n\u2019a pas acc\u00e8s \u00e0 la variable d\u2019ex\u00e9cution MULTI-VOIES.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Pour les simulations avec mod\u00e8le GTD et le mod\u00e8le CIVA_GTD_MV qui n\u2019aboutissent pas \u00e0 un bon accord avec l\u2019exp\u00e9rience, les \u00e9carts s\u2019expliquent par la non prise en compte de l\u2019ouverture de l\u2019entaille lors du calcul des \u00e9chos de bord bas. Ce sont des calculs \u00ab 2D \u00bb r\u00e9alis\u00e9s avec CIVA_ATHENA_2D qui ont permis d\u2019aboutir \u00e0 cette hypoth\u00e8se. Cependant, ces calculs doivent \u00eatre confirm\u00e9s en \u00ab 3D \u00bb quand un mod\u00e8le le permettant sera disponible.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h2 class=\"titre-accordeon\">Explications des ecarts entre l&rsquo;exp\u00e9rience et le mod\u00e8le GTD<\/h2>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h2 class=\"titre-paragraphe\">Approximation du champ dans CIVA<\/h2>\n<p>&nbsp;<\/p>\n<p>En TOFD, le calcul de l\u2019\u00e9cho de diffraction du bord bas d\u2019une entaille utilise une description simplifi\u00e9e du champ ultrasonore \u00e9mis par chaque capteur mono\u00e9l\u00e9ment. La simplification concerne la forme temporelle, la direction d\u2019incidence, l\u2019amplitude, la phase et le temps de vol. La validit\u00e9 de cette approximation d\u00e9pend donc de la position du bord de l\u2019entaille dans le champ des capteurs. Ainsi, elle n\u2019est plus valable quand la profondeur du bord bas de l\u2019entaille est tr\u00e8s \u00e9loign\u00e9e de celle du point de croisement des axes capteurs, c\u2019est \u00e0 dire pour une distance \u00ab\u00a0D\u00a0\u00bb grande (cf. figure ci-dessous) et lorsque le bord bas n\u2019est plus dans les zones de champ intense.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"182\" class=\"alignnone wp-image-3168\" src=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_25.png\" alt=\"\" srcset=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_25.png 600w, https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_25-300x91.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>De plus, pour une distance \u00ab D \u00bb donn\u00e9e, la validit\u00e9 de la description approch\u00e9e du champ est r\u00e9duite lorsque la distance \u00ab Di \u00bb entre le bord bas et le point d\u2019impact du capteur est petite (cas de la configuration de gauche sur la figure ci-dessus), ce qui va de pair avec des probl\u00e8mes connus de validit\u00e9 des pr\u00e9dictions de CIVA en champ proche.<\/p>\n<p>&nbsp;<\/p>\n<p>La variable d\u2019ex\u00e9cution \u00ab\u00a0MULTI VOIES\u00a0\u00bb de CIVA permet de s\u2019affranchir de cette approximation. Chaque capteur mono\u00e9l\u00e9ment est remplac\u00e9 par un capteur multi\u00e9l\u00e9ments de 249 \u00e9l\u00e9ments de m\u00eame forme. Cela permet une description plus pr\u00e9cise du champ utilis\u00e9 par le mod\u00e8le GTD lors du calcul de l\u2019interaction avec les entailles. En effet, alors qu\u2019avec des capteurs mono\u00e9l\u00e9ment, c\u2019est le champ global qui est simplifi\u00e9, avec des capteurs multi\u00e9l\u00e9ments, c\u2019est chaque champ \u00e9l\u00e9mentaire qui est d\u00e9crit de mani\u00e8re simplifi\u00e9e. La variable d\u2019ex\u00e9cution \u00ab\u00a0MULTI VOIES\u00a0\u00bb permet de calculer la r\u00e9ponse du bord bas en prenant compte au niveau de chaque point d\u00e9crivant le bord, non pas le champ global form\u00e9 par les capteurs mono\u00e9l\u00e9ment mais les 249 champs \u00e9l\u00e9mentaires de chaque capteurs multil\u00e9ments, ce qui permet une description plus pr\u00e9cise du champ.<\/p>\n<p>&nbsp;<\/p>\n<h2 class=\"titre-paragraphe\">Non prise en compte de l\u2019ouverture des entailles<\/h2>\n<p>&nbsp;<\/p>\n<p>La figure ci-dessous illustre la propagation d\u2019ondes rasantes (L et T) le long de l\u2019ouverture d\u2019une entaille.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" width=\"312\" height=\"165\" class=\"alignnone wp-image-3169\" src=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_26.png\" alt=\"\" srcset=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_26.png 312w, https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_26-300x159.png 300w\" sizes=\"auto, (max-width: 312px) 100vw, 312px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Ces ondes, tr\u00e8s proches temporellement, peuvent modifier l\u2019amplitude des \u00e9chos des bords bas. Elles se manifestent surtout aux petits angles d\u2019incidence \u03b8 sur le bord bas, donc aux petites PCS. Elles sont prises en compte avec le mod\u00e8le GTD mais uniquement dans le cas o\u00f9 elles ont le m\u00eame temps de vol puisque la GTD n\u2019est valable que pour des entailles d\u2019ouverture quasi-nulle.<\/p>\n<p>&nbsp;<\/p>\n<p>Ainsi, pour prendre en compte ces ondes dans le cas des entailles d\u2019ouverture 0.2mm, CIVA_ATHENA_2D a \u00e9t\u00e9 utilis\u00e9. C\u2019est le seul mod\u00e8le \u00ab 2D \u00bb qui permette de prendre en compte l\u2019ouverture des entailles. Les \u00e9chos de bord bas d\u2019entailles ouvertes d\u00e9crites par des d\u00e9fauts de type \u00ab multifacettes \u00bb d\u2019ouverture rectangulaire de 0.2mm et ceux d\u2019entailles d\u2019ouverture quasi-nulle ont donc \u00e9t\u00e9 calcul\u00e9s avec ce mod\u00e8le et compar\u00e9s entre eux.<\/p>\n<p>&nbsp;<\/p>\n<p>Enfin, il est \u00e0 noter que les effets de la non prise en compte de l\u2019ouverture de l\u2019entaille peuvent se combiner \u00e0 ceux de l\u2019approximation du champ dans CIVA.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h2 class=\"titre-accordeon\">Comparaison des Ascans<\/h2>\n<p>&nbsp;<\/p>\n<p>En plus des amplitudes des \u00e9chos de diffraction de bord bas, les Ascans simul\u00e9s (avec CIVA_GTD et CIVA_GTD_MV) et exp\u00e9rimentaux ont \u00e9t\u00e9 compar\u00e9s.<\/p>\n<p>&nbsp;<\/p>\n<p>L\u2019\u00e9tude de comparaison sur les Ascans montre que lorsque les amplitudes sont en bon accord, les Ascans le sont \u00e9galement. La figure ci-dessous illustre le bon accord entre les Ascans simul\u00e9s et exp\u00e9rimentaux dans le cas de l\u2019inspection en L60\u00b0 avec une PCS de 38mm.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"357\" class=\"alignnone wp-image-3170\" src=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_27.png\" alt=\"\" srcset=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_27.png 500w, https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_27-300x214.png 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Lorsque les amplitudes pr\u00e9dites par CIVA_GTD ne sont pas en bon accord avec les amplitudes exp\u00e9rimentales, la superposition des Ascans peut \u00eatre plus ou moins bonne en fonction de la cause des \u00e9carts en amplitude. Ainsi, si la description approch\u00e9e du champ est responsable \u00a0des diff\u00e9rences en amplitudes entre simulation et exp\u00e9rience, alors les Ascans simul\u00e9s et mesur\u00e9s ne sont pas en bon accord (cf. figure ci-dessous pour l\u2019entaille de hauteur 7.5mm d\u00e9tect\u00e9e en OL45\u00b0).<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" width=\"444\" height=\"191\" class=\"alignnone wp-image-3171\" src=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_28.png\" alt=\"\" srcset=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_28.png 444w, https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_28-300x129.png 300w\" sizes=\"auto, (max-width: 444px) 100vw, 444px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Par ailleurs, il est \u00e0 noter que dans les cas o\u00f9 les Ascans simul\u00e9s avec CIVA_GTD ne sont pas en bon accord avec les Ascans exp\u00e9rimentaux alors les Ascans obtenus avec CIVA_GTD_MV sont souvent beaucoup plus proches des Ascans exp\u00e9rimentaux (cf. figure ci-dessous pour les entailles de hauteur 10mm et 7.5mm d\u00e9tect\u00e9es en OL45\u00b0).<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"130\" class=\"alignnone wp-image-3172\" src=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_29.png\" alt=\"\" srcset=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_29.png 700w, https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_29-300x56.png 300w, https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_29-600x111.png 600w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"158\" class=\"alignnone wp-image-3173\" src=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_30.png\" alt=\"\" srcset=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_30.png 600w, https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_30-300x79.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>En revanche, si la cause des \u00e9carts en amplitude est li\u00e9e \u00e0 la non prise en compte de l\u2019ouverture de l\u2019entaille, alors les Ascans simul\u00e9s et exp\u00e9rimentaux se superposent bien (cf. figure ci-dessous pour l\u2019entaille de hauteur 7.5mm d\u00e9tect\u00e9e en OL60\u00b0).<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"132\" class=\"alignnone wp-image-3174\" src=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_31.png\" alt=\"\" srcset=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_31.png 700w, https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_31-300x57.png 300w, https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_31-600x113.png 600w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>La prise en compte de l\u2019ouverture de l\u2019entaille ne change pas la forme des Ascans. Cela a \u00e9t\u00e9 v\u00e9rifi\u00e9 en comparant des Ascans obtenus avec CIVA_ATHENA_2D.<\/p>\n<p>&nbsp;<\/p>\n<p>La figure ci-dessous montre les Ascans obtenus pour des configurations o\u00f9 la prise en compte de l\u2019ouverture de l\u2019entaille influe sur l\u2019amplitude des \u00e9chos de diffractions (OL60\u00b0, entaille de hauteur 15mm et 12.5mm).<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"170\" class=\"alignnone wp-image-3175\" src=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_32.png\" alt=\"\" srcset=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_32.png 600w, https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_32-300x85.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Il y a un tr\u00e8s bon accord des Ascans avec et sans prise en compte de l\u2019ouverture de l\u2019entaille.<\/p>\n<p>&nbsp;<\/p>\n<p>Cela a \u00e9t\u00e9 v\u00e9rifi\u00e9 \u00e9galement pour les configurations o\u00f9 l\u2019ouverture de l\u2019entaille \u00e9tait responsable d\u2019\u00e9carts en amplitude entre la simulation et l\u2019exp\u00e9rience (par exemple\u00a0: configuration OL45\u00b0).<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"173\" class=\"alignnone wp-image-3176\" src=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_33.png\" alt=\"\" srcset=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_33.png 700w, https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_33-300x74.png 300w, https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/Figure_33-600x148.png 600w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h2 class=\"titre-accordeon\">Conclusion<\/h2>\n<p>&nbsp;<\/p>\n<p>L\u2019\u00e9tude des \u00e9chos de diffraction des bords bas d\u2019entailles de diff\u00e9rentes hauteurs d\u00e9tect\u00e9s par la m\u00e9thode TOFD avec des capteurs L60\u00b0, L45\u00b0 et L70\u00b0 et des PCS variables \u00a0a montr\u00e9 :<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li>un bon accord entre les amplitudes des \u00e9chos exp\u00e9rimentaux et simul\u00e9s par le mod\u00e8le GTD de CIVA11.0a :<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul style=\"list-style-type: circle; margin-left: 80px;\">\n<li>si le point de croisement des axes des capteurs est assez proche du bord bas de l\u2019entaille<\/li>\n<li><u>ET<\/u> si l\u2019angle d\u2019incidence \u03b8 des ondes L sur le bord est tel que l\u2019ouverture de l\u2019entaille n\u2019a pas d\u2019effet sur l\u2019\u00e9cho (\u03b8 sup\u00e9rieur \u00e0 50\u00b0- 55\u00b0 dans le cas des capteurs de fr\u00e9quence centrale 5MHz utilis\u00e9s pour cette \u00e9tude).<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li>des \u00e9carts dans les cas o\u00f9 la profondeur du bord bas s\u2019\u00e9loigne de celle du point de croisement des axes des capteurs ou lorsque les angles \u03b8 sont inf\u00e9rieurs \u00e0 50\u00b0-55\u00b0 environ. CIVA sous-estime alors les amplitudes par rapport \u00e0 la mesure. Il est alors possible de r\u00e9duire ces \u00e9carts de deux fa\u00e7ons:\n<ul style=\"list-style-type: circle;\">\n<li>en s\u2019affranchissant de l\u2019approximation du champ dans CIVA pour le calcul de l\u2019interaction faisceau\/entaille. Cette approximation n\u2019est plus valable quand le bord bas est tr\u00e8s \u00e9loign\u00e9 du point de croisement des axes des capteurs. Les simulations avec le mod\u00e8le GTD + la variable d\u2019ex\u00e9cution MULTIVOIES (disponible pour les utilisateurs internes uniquement) ont montr\u00e9 que les amplitudes des \u00e9chos de bord bas pr\u00e9dites par CIVA sont plus \u00e9lev\u00e9es que celles obtenues avec la GTD et aussi plus proches de la mesure\u00a0; idem pour les A-scans.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul style=\"list-style-type: circle; margin-left: 80px;\">\n<li>en prenant en compte l\u2019ouverture r\u00e9elle des entailles usin\u00e9es dans la pi\u00e8ce et en simulant les ondes pouvant se propager le long de cette ouverture. Cette prise en compte entra\u00eene une modification de l\u2019amplitude surtout aux petits angles d\u2019incidence des ondes L sur le bord bas. Des simulations \u00ab 2D \u00bb r\u00e9alis\u00e9es avec ATHENA_2D et un d\u00e9faut multi-facette d\u00e9crivant une entaille ouverte ont montr\u00e9 que les amplitudes pr\u00e9dites par ATHENA_2D pour des entailles ouvertes sont plus \u00e9lev\u00e9es que celles des entailles d\u2019ouverture quasi-nulle. Ainsi, on peut supposer qu\u2019en \u00ab 3D \u00bb, les amplitudes simul\u00e9es se rapprocheraient de la mesure en prenant en compte l\u2019ouverture.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p style=\"margin-left: 80px;\">Il est \u00e0 noter que l\u2019affranchissement de l\u2019approximation sur le champ et de l\u2019ouverture des entailles ne modifie pas les r\u00e9sultats qui pr\u00e9sentaient d\u00e9j\u00e0 un bon accord entre simulation et exp\u00e9rience.<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"line-height: 1.5em;\">A noter que les entailles \u00ab r\u00e9elles \u00bb (non usin\u00e9es) ont une ouverture quasi-nulle ; le mod\u00e8le GTD ou GTD + la variable d\u2019ex\u00e9cution MULTI-VOIES doivent permettre de simuler correctement les \u00e9chos de bord bas de ces entailles.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Continuer vers <a class=\"lien\" href=\"https:\/\/extende.realisateurweb.com\/fr\/la-simulation-cnd\/documentation\/validation-experimentale-des-modeles-civa\/validation-experimentale-des-modeles-civa-en-ultrasons\/ultrasons-tofd\/ut-tofd-resultats-sur-les-echos-de-fond\/\">R\u00e9sultats sur les \u00e9chos de fond<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Retour vers <a class=\"g-lien\" href=\"https:\/\/extende.realisateurweb.com\/fr\/la-simulation-cnd\/documentation\/validation-experimentale-des-modeles-civa\/validation-experimentale-des-modeles-civa-en-ultrasons\/ultrasons-tofd\/\">TOFD<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Extende, Simulation en contr\u00f4le non destructif, logiciel CIVA, ultrasons, courants de Foucault, Radiographie, conception de sondes, POD, Qualifications<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":2913,"menu_order":4,"comment_status":"closed","ping_status":"closed","template":"templates\/page--extende.html.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-3235","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/extende.realisateurweb.com\/fr\/wp-json\/wp\/v2\/pages\/3235","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/extende.realisateurweb.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/extende.realisateurweb.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/extende.realisateurweb.com\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/extende.realisateurweb.com\/fr\/wp-json\/wp\/v2\/comments?post=3235"}],"version-history":[{"count":2,"href":"https:\/\/extende.realisateurweb.com\/fr\/wp-json\/wp\/v2\/pages\/3235\/revisions"}],"predecessor-version":[{"id":6778,"href":"https:\/\/extende.realisateurweb.com\/fr\/wp-json\/wp\/v2\/pages\/3235\/revisions\/6778"}],"up":[{"embeddable":true,"href":"https:\/\/extende.realisateurweb.com\/fr\/wp-json\/wp\/v2\/pages\/2913"}],"wp:attachment":[{"href":"https:\/\/extende.realisateurweb.com\/fr\/wp-json\/wp\/v2\/media?parent=3235"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}