{"id":4258,"date":"2025-06-24T18:37:16","date_gmt":"2025-06-24T16:37:16","guid":{"rendered":""},"modified":"2025-06-24T18:52:11","modified_gmt":"2025-06-24T16:52:11","slug":"echos-de-coin-en-ondes-t-conclusion-et-explications-des-phenomenes","status":"publish","type":"page","link":"https:\/\/extende.realisateurweb.com\/fr\/la-simulation-cnd\/documentation\/validation-experimentale-des-modeles-civa\/validation-experimentale-des-modeles-civa-en-ultrasons\/ultrasons-echos-de-coin\/echos-de-coin-en-ondes-t\/echos-de-coin-en-ondes-t-conclusion-et-explications-des-phenomenes\/","title":{"rendered":"Echos de coin en ondes T : Conclusion et explications des ph\u00e9nom\u00e8nes"},"content":{"rendered":"<h2 class=\"titre-accordeon\">CONCLUSION<\/h2>\n<\/p>\n<p class=\"titre-paragraphe\">\n<\/p>\n<p class=\"titre-paragraphe\">Un bon accord est observ\u00e9 entre les r\u00e9sultats exp\u00e9rimentaux et simul\u00e9s sur les \u00e9chos de coin obtenus en ondes T lorsque l\u2019entaille est plus grande que la longueur d\u2019onde. Dans ce cas, l\u2019\u00e9cart sur l\u2019amplitude maximale entre l\u2019exp\u00e9rience et la simulation ne d\u00e9passe que tr\u00e8s rarement les 2 dB.<br \/>\nLes \u00e9carts plus importants sont observ\u00e9s lorsque les entailles sont petites par rapport \u00e0 la longueur d\u2019onde ou lorsqu\u2019elles en sont tr\u00e8s proches.<\/p>\n<\/p>\n<p class=\"titre-paragraphe\">Des \u00e9tudes plus approfondies vont continuer sur ce sujet.<\/p>\n<\/p>\n<p class=\"titre-paragraphe\">\u00a0<\/p>\n<\/p>\n<p class=\"titre-paragraphe\">\n<\/p>\n<h2 class=\"titre-accordeon\">EXPLICATION DES PH\u00c9NOM\u00c8NES<\/h2>\n<\/p>\n<p class=\"titre-paragraphe\">\n<\/p>\n<p class=\"titre-paragraphe\">On observe que l\u2019\u00e9cart entre la simulation et l\u2019exp\u00e9rience augmente quand on utilise un traducteur divergent et quand le rapport de la dimension de l\u2019entaille et de la longueur d\u2019onde d\u00e9cro\u00eet. Plusieurs hypoth\u00e8ses peuvent \u00eatre propos\u00e9es pour expliquer les \u00e9carts observ\u00e9s :<\/p>\n<\/p>\n<ul class=\"liste-carres-noirs\">\n<li>\n<div class=\"titre-paragraphe\">La limitation \u00ab petits d\u00e9fauts \u00bb du mod\u00e8le d\u2019interaction de Kirchhoff<\/div>\n<\/li>\n<li>\n<div class=\"titre-paragraphe\">Les limites de la mod\u00e9lisation du champ<\/div>\n<\/li>\n<li>\n<div class=\"titre-paragraphe\">Les contributions critiques, ou ondes rampantes, en particulier pour des faisceaux divergents<\/div>\n<\/li>\n<li>\n<div class=\"titre-paragraphe\">Le d\u00e9calage et le d\u00e9doublement des \u00e9chos aux grands angles d\u2019incidence<\/div>\n<\/li>\n<\/ul>\n<div class=\"titre-paragraphe\">\u00a0<\/div>\n<\/p>\n<h2 class=\"titre-paragraphe\">Limitation \u00ab\u00a0petits d\u00e9fauts\u00a0\u00bb du mod\u00e8le de Kirchhoff<\/h2>\n<\/p>\n<p><span style=\"line-height: 1.5em;\">Dans certains cas, comme pour le capteur au contact de \u00d86,35 mm fonctionnant \u00e0 2,25 MHz ou les capteurs en immersion fonctionnant \u00e0 2,25 MHz, des \u00e9carts entre simulation et exp\u00e9rience peuvent apparaitre, en particulier pour les petits d\u00e9fauts. Les limitations du mod\u00e8le d\u2019interaction expliquent en partie ces diff\u00e9rences.<\/span><\/p>\n<\/p>\n<p class=\"titre-paragraphe\">Le mod\u00e8le d\u2019interaction champ-d\u00e9faut de Kirchhoff a \u00e9t\u00e9 d\u00e9velopp\u00e9 pour les r\u00e9flexions sp\u00e9culaires \u00e0 haute fr\u00e9quence. Cela impose que le rayon des d\u00e9fauts (ici, la demi-hauteur des entailles) doit \u00eatre tr\u00e8s sup\u00e9rieure \u00e0 la longueur d\u2019onde et que les contributions associ\u00e9es \u00e0 la diffraction par les ar\u00eates des entailles ne sont pas simul\u00e9es. La validit\u00e9 du mod\u00e8le est assur\u00e9e selon un crit\u00e8re bas\u00e9 sur le produit du nombre d\u2019onde (k = 2*\u03c0\/\u03bb) avec le rayon du d\u00e9faut (a) : k.a&gt;&gt;1.<\/p>\n<\/p>\n<p class=\"titre-paragraphe\">A 2 MHz, pour une vitesse de phase correspondant \u00e0 celle des ondes L dans l\u2019acier (5900 m\/s), k vaut 2,2 mm^-1 ce qui impose que la hauteur de l\u2019entaille doit \u00eatre grande par rapport \u00e0 0,9 mm. Cela explique pourquoi la simulation pour des entailles de 0,5 mm ou 1 mm est moins pr\u00e9cise.<\/p>\n<\/p>\n<p class=\"titre-paragraphe\"><strong>Mise \u00e0 jour : La limite petits d\u00e9fauts du mod\u00e8le d&rsquo;interaction Kirchhoff peut \u00eatre contourn\u00e9e dans CIVA gr\u00e2ce au mod\u00e8le d&rsquo;\u00e9l\u00e9ments finis transitoires (TFEM) disponible depuis CIVA 2020. Le TFEM ne souffre pas de cette limitation et permet de simuler tous les ph\u00e9nom\u00e8nes d&rsquo;interaction physique entre le champ et le d\u00e9faut, y compris les ondes rampantes et les ondes de Rayleigh.<\/strong><\/p>\n<\/p>\n<p class=\"titre-paragraphe\">De plus, il est mis en \u00e9vidence que la fr\u00e9quence centrale du traducteur n\u2019est pas le seul param\u00e8tre influant dans la limitation de Kirchhoff, la bande passante a aussi une influence. Cependant, l\u2019influence de la bande passante n\u2019est pas trait\u00e9e dans ce document puisque, pour tous les traducteurs utilis\u00e9s dans cette \u00e9tude, elle est \u00e9gale \u00e0 environ 60%.<\/p>\n<\/p>\n<p>\u00a0<\/p>\n<\/p>\n<h2 class=\"titre-paragraphe\">Les limites de la mod\u00e9lisation du champ<\/h2>\n<\/p>\n<p><span style=\"line-height: 1.5em;\">Contrairement aux courbes exp\u00e9rimentales, les courbes \u00e9chodynamiques, simul\u00e9es avec CIVA, sur des TGs situ\u00e9s \u00e0 diff\u00e9rentes profondeurs sont parfois dissym\u00e9triques. De plus, les amplitudes peuvent \u00eatre sous-estim\u00e9es. Ce ph\u00e9nom\u00e8ne est en particulier observ\u00e9 avec <a class=\"g-lien\" href=\"https:\/\/extende.realisateurweb.com\/fr\/la-simulation-cnd\/documentation\/validation-experimentale-des-modeles-civa\/validation-experimentale-des-modeles-civa-en-ultrasons\/ultrasons-echos-de-coin\/echos-de-coin-en-ondes-t\/echos-de-coin-en-ondes-t-influence-de-la-hauteur-de-lentaille\/\" target=\"_self\">les capteurs en immersion \u00e0 2,25 MHz<\/a>.<\/span><\/p>\n<\/p>\n<p>\u00a0<\/p>\n<\/p>\n<p class=\"titre-paragraphe\" style=\"text-align: center;\"><a class=\"mediabox\" href=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/CIVA-Validation-UT-CoinOT8-1.png\" style=\"text-decoration: none;\" title=\"\"><img loading=\"lazy\" decoding=\"async\" align=\"\" alt=\"\" class=\"mediabox alignnone wp-image-4246\" height=\"198\" src=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/CIVA-Validation-UT-CoinOT8-1.png\" width=\"400\" srcset=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/CIVA-Validation-UT-CoinOT8-1.png 778w, https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/CIVA-Validation-UT-CoinOT8-1-300x149.png 300w, https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/CIVA-Validation-UT-CoinOT8-1-768x381.png 768w, https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/CIVA-Validation-UT-CoinOT8-1-600x298.png 600w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a><\/p>\n<\/p>\n<p class=\"titre-paragraphe\">\u00a0<\/p>\n<\/p>\n<p class=\"titre-paragraphe\">Ce ph\u00e9nom\u00e8ne apparait \u00e9galement lors de l\u2019inspection d\u2019entailles de grandes hauteurs (pour les entailles de faibles hauteurs, d\u2019autres ph\u00e9nom\u00e8nes peuvent s\u2019ajouter). Les figures ci-dessous correspondent aux C-scans mesur\u00e9s et simul\u00e9s de l\u2019\u00e9cho de coin obtenu pour une entaille haute de 15 \u00a0mm. On peut remarquer la r\u00e9ponse asym\u00e9trique de l\u2019entaille : la r\u00e9ponse exp\u00e9rimentale est moins \u00ab \u00e9tendue \u00bb que celle simul\u00e9e. Le c\u00f4t\u00e9 gauche des r\u00e9sultats suivants est correctement estim\u00e9, tandis que les \u00e9chos sont \u00ab \u00e9tal\u00e9s \u00bb du c\u00f4t\u00e9 droit sur les C-scans ci-dessous lorsqu\u2019on utilise des capteurs en immersion \u00e0 2,25 MHz.<\/p>\n<\/p>\n<p class=\"titre-paragraphe\">\u00a0<\/p>\n<\/p>\n<div class=\"corner-wrapper\">\n<div class=\"corner-frame\">Note : Les directions de balayage sont invers\u00e9es entre les 2 cas.<\/div>\n<\/div>\n<p class=\"titre-paragraphe\">\u00a0<\/p>\n<\/p>\n<p class=\"titre-paragraphe\" style=\"text-align: center;\"><a class=\"mediabox\" href=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/CIVA-Validation-UT-CoinOT8-2.png\" style=\"text-decoration: none;\" title=\"\"><img loading=\"lazy\" decoding=\"async\" align=\"\" alt=\"\" class=\"mediabox alignnone wp-image-4247\" height=\"117\" src=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/CIVA-Validation-UT-CoinOT8-2.png\" width=\"400\" srcset=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/CIVA-Validation-UT-CoinOT8-2.png 841w, https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/CIVA-Validation-UT-CoinOT8-2-300x88.png 300w, https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/CIVA-Validation-UT-CoinOT8-2-768x225.png 768w, https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/CIVA-Validation-UT-CoinOT8-2-600x176.png 600w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a><\/p>\n<\/p>\n<p class=\"titre-paragraphe\">\u00a0<\/p>\n<\/p>\n<p class=\"titre-paragraphe\">Les \u00e9carts observ\u00e9s sur les courbes \u00e9chodynamiques associ\u00e9es aux TGs et aux entailles peuvent donc \u00eatre dus \u00e0 un probl\u00e8me de mod\u00e9lisation du champ. En effet, les hypoth\u00e8ses faites pour simplifier la description du champ dans le module de calcul d\u2019\u00e9cho peuvent expliquer l\u2019\u00e9cart entre la simulation et l\u2019exp\u00e9rience sur les \u00e9chos de coin. Au voisinage d\u2019un point d\u2019\u00e9chantillonnage de l\u2019entaille, les fronts d\u2019onde sont suppos\u00e9s \u00eatre localement plans. Or, plus le capteur est de dimension r\u00e9duite, moins cette hypoth\u00e8se est v\u00e9rifi\u00e9e, idem lorsque le d\u00e9faut se trouve en dehors de la zone focale du traducteur c\u2019est \u00e0 dire dans le champ tr\u00e8s lointain ou dans le champ tr\u00e8s proche du traducteur.<\/p>\n<\/p>\n<p class=\"titre-paragraphe\">Un \u00e9talonnage \u00e0 une profondeur diff\u00e9rente pourrait permettre de limiter l\u2019\u00e9cart d\u2019amplitude mais ne supprimerait pas l\u2019erreur dans la forme des r\u00e9sultats.<\/p>\n<\/p>\n<p><strong>Mise \u00e0 jour : Le mod\u00e8le Full Beam (Champ Complet) disponible dans les derni\u00e8res versions de CIVA ne fait pas l&rsquo;hypoth\u00e8se que les fronts d&rsquo;onde sont plans pr\u00e8s du d\u00e9faut contrairement au mod\u00e8le d&rsquo;approximation d&rsquo;onde plane. Les simulations avec le mod\u00e8le Full beam (Champ Complet) devraient donc am\u00e9liorer la pr\u00e9diction du faisceau dans ces configurations.<\/strong><\/p>\n<\/p>\n<h2 class=\"titre-paragraphe\">Les contributions critiques, ou ondes rampantes, en particulier pour des faisceaux divergents<\/h2>\n<\/p>\n<p><span style=\"line-height: 1.5em;\">Ces ph\u00e9nom\u00e8nes sont dus \u00e0 la pr\u00e9sence d\u2019ondes dans le faisceau arrivant sur le fond de la pi\u00e8ce et\/ou la surface de l\u2019entaille \u00e0 des incidences plus \u00e9lev\u00e9es que l\u2019incidence critique. Des ondes de surface peuvent \u00eatre alors g\u00e9n\u00e9r\u00e9es. On rappelle que l\u2019angle de r\u00e9fraction des ondes T correspondant \u00e0 l\u2019incidence critique pour l\u2019acier est de 33\u00b0 sur le fond et de 57\u00b0 sur une entaille verticale). Les contributions des ondes rasantes et des ondes de t\u00eate peuvent \u00eatre \u00e0 l\u2019origine des divergences observ\u00e9es sur les courbes d\u2019\u00e9chodynamiques puisqu\u2019elles donnent lieu \u00e0 des contributions suppl\u00e9mentaires \u00e0 l\u2019\u00e9cho de coin.<\/span><\/p>\n<\/p>\n<p class=\"titre-paragraphe\">Ce ph\u00e9nom\u00e8ne pourrait expliquer une partie des diff\u00e9rences observ\u00e9es avec le <a class=\"g-lien\" href=\"https:\/\/extende.realisateurweb.com\/fr\/la-simulation-cnd\/documentation\/validation-experimentale-des-modeles-civa\/validation-experimentale-des-modeles-civa-en-ultrasons\/ultrasons-echos-de-coin\/echos-de-coin-en-ondes-t\/echos-de-coin-en-ondes-t-influence-de-la-hauteur-de-lentaille\/\" target=\"_self\">capteur en immersion de \u00d86,35 mm et fonctionnant \u00e0 2,25 MHz<\/a>.\u00a0<\/p>\n<\/p>\n<p class=\"titre-paragraphe\">\u00a0<\/p>\n<\/p>\n<div style=\"text-align: center;\"><a class=\"mediabox\" href=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/CIVA-Validation-UT-CoinOT8-3.png\" style=\"text-decoration: none; line-height: 1.5em;\" title=\"\"><img loading=\"lazy\" decoding=\"async\" align=\"\" alt=\"\" class=\"mediabox alignnone wp-image-4248\" height=\"209\" src=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/CIVA-Validation-UT-CoinOT8-3.png\" width=\"200\"><\/a><span style=\"line-height: 1.5em;\">\u00a0\u00a0<\/span><\/div>\n<\/p>\n<p>\u00a0<\/p>\n<\/p>\n<p>L\u2019image ci-dessus montre la contribution des ondes rasantes et de t\u00eate sur l\u2019\u00e9cho de coin dans la configuration \u00e9tudi\u00e9e, c\u2019est \u00e0 dire une inspection T45 d\u2019une pi\u00e8ce plane en acier et selon un angle critique de 33\u00b0 ; les ondes rasantes sont repr\u00e9sent\u00e9es en vert. Il est \u00e0 noter que la version 10.1 de CIVA ne calcule que les ondes rampantes en fond de pi\u00e8ce. Celles qui se propagent sur la surface d\u2019entr\u00e9e de la pi\u00e8ce ou bien celle se propageant sur l\u2019entaille (ce qui est notre cas ici) ne sont pas mod\u00e9lis\u00e9es par CIVA. On comprend alors les \u00e9carts entre la simulation et l\u2019exp\u00e9rience. Le travail de mod\u00e9lisation de ces ondes rampantes en surface et sur l\u2019entaille est en cours. La prise en compte de ces contributions pourraient \u00eatre disponible dans une prochaine version de CIVA. On pr\u00e9cise tout de m\u00eame que ces contributions sont d\u2019ores et d\u00e9j\u00e0 prises en compte par le module CIVA-Athena2D.<\/p>\n<\/p>\n<p><strong>Mise \u00e0 jour : Dans CIVA 2021, l&rsquo;approximation d&rsquo;onde plane et le mod\u00e8le Champ Complet (Full Beam) pour l&rsquo;interaction champ\/d\u00e9faut ne permettent toujours pas la simulation de l&rsquo;onde rampante sur l&rsquo;entaille. Cependant, depuis CIVA 2020, le mod\u00e8le transitoire par \u00e9l\u00e9ments finis (TFEM)\u00a0 permet de consid\u00e9rer tous les ph\u00e9nom\u00e8nes qui peuvent se produire lors de l&rsquo;interaction champ\/d\u00e9faut, y compris le ph\u00e9nom\u00e8ne d&rsquo;onde rampante. Ceci explique pourquoi les simulations avec TFEM montrent un bon accord avec l&rsquo;exp\u00e9rience.<\/strong><\/p>\n<\/p>\n<p><span style=\"line-height: 1.5em;\">La simulation du champ r\u00e9fract\u00e9 dans la pi\u00e8ce par le traducteur contact T45 de dimension 22\u00d720 mm, fonctionnant \u00e0 2 MHz est repr\u00e9sent\u00e9e ci-dessous.<\/span><\/p>\n<\/p>\n<p class=\"titre-paragraphe\">Sur la cartographie, les directions locales du champ \u00e9mis au niveau de chaque point de la zone de calcul sont affich\u00e9es : elles sont repr\u00e9sent\u00e9es par de petites fl\u00e8ches indiquant l\u2019orientation du faisceau au point correspondant.<\/p>\n<\/p>\n<p class=\"titre-paragraphe\">Le faisceau de ce traducteur n\u2019est pas divergent autour des entailles en raison des dimensions de la pastille et parce que la profondeur des entailles (50 mm) est proche de celle \u00e0 laquelle on mesure l\u2019amplitude maximale du champ. Dans la largeur \u00ab principale \u00bb du faisceau (d\u00e9limit\u00e9e par les lignes \u00e0 -6 dB), les fronts sont plans et sont orient\u00e9s selon une direction de propagation d\u2019environ 43,5\u00b0. Il n\u2019y a pas de rayons critiques dans cette partie du champ et les ph\u00e9nom\u00e8nes critiques sur le fond (ondes rampantes et de t\u00eate) n\u2019ont aucun effet.<\/p>\n<\/p>\n<p class=\"titre-paragraphe\">\u00a0<\/p>\n<\/p>\n<p class=\"titre-paragraphe\" style=\"text-align: center;\"><a class=\"mediabox\" href=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/CIVA-Validation-UT-CoinOT8-4.png\" style=\"text-decoration: none;\" title=\"\"><img loading=\"lazy\" decoding=\"async\" align=\"\" alt=\"\" class=\"mediabox alignnone wp-image-4249\" height=\"318\" src=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/CIVA-Validation-UT-CoinOT8-4.png\" width=\"400\" srcset=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/CIVA-Validation-UT-CoinOT8-4.png 612w, https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/CIVA-Validation-UT-CoinOT8-4-300x239.png 300w, https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/CIVA-Validation-UT-CoinOT8-4-600x477.png 600w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a><\/p>\n<\/p>\n<p class=\"titre-paragraphe\">\u00a0<\/p>\n<\/p>\n<p class=\"titre-paragraphe\">En fonction de la position du traducteur par rapport \u00e0 l\u2019entaille, la position de l\u2019entaille change dans le faisceau comme illustr\u00e9 sur la figure ci-dessous. Par cons\u00e9quent, l\u2019angle d\u2019incidence sur la surface de l\u2019entaille varie aussi. Pour une position donn\u00e9e du traducteur, ces angles correspondent \u00e0 ceux indiqu\u00e9s le long d\u2019une ligne verticale sur la figure suivante.<\/p>\n<\/p>\n<p class=\"titre-paragraphe\">\u00a0<\/p>\n<\/p>\n<p class=\"titre-paragraphe\" style=\"text-align: center;\"><a class=\"mediabox\" href=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/CIVA-Validation-UT-CoinOT8-5.png\" style=\"text-decoration: none;\" title=\"\"><img loading=\"lazy\" decoding=\"async\" align=\"\" alt=\"\" class=\"mediabox alignnone wp-image-4250\" height=\"146\" src=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/CIVA-Validation-UT-CoinOT8-5.png\" width=\"400\" srcset=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/CIVA-Validation-UT-CoinOT8-5.png 812w, https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/CIVA-Validation-UT-CoinOT8-5-300x110.png 300w, https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/CIVA-Validation-UT-CoinOT8-5-768x282.png 768w, https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/CIVA-Validation-UT-CoinOT8-5-600x220.png 600w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a><\/p>\n<\/p>\n<p class=\"titre-paragraphe\">\u00a0<\/p>\n<\/p>\n<p class=\"titre-paragraphe\">Nous pouvons voir que les rayons qui arrivent sur le d\u00e9faut ne le font pas \u00e0 des incidences critiques (les incidences critiques sont d\u2019environ 57\u00b0 sur une entaille verticale). Il n\u2019y a donc pas de ph\u00e9nom\u00e8nes critiques sur la surface de l\u2019entaille.<\/p>\n<p>A la profondeur correspondant au fond de pi\u00e8ce, le faisceau rayonn\u00e9 par un capteur de \u00d812,7 mm, fonctionnant \u00e0 2,25 MHz, est orient\u00e9, \u00e0 -6 dB, entre 41\u00b0 et 50\u00b0 (voir figure ci-dessous). Les contributions critiques peuvent encore \u00eatre n\u00e9glig\u00e9es.<\/p>\n<\/p>\n<p class=\"titre-paragraphe\">\u00a0<\/p>\n<\/p>\n<p class=\"titre-paragraphe\" style=\"text-align: center;\"><a class=\"mediabox\" href=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/CIVA-Validation-UT-CoinOT8-6.jpg\" style=\"text-decoration: none;\" title=\"\"><img loading=\"lazy\" decoding=\"async\" align=\"\" alt=\"\" class=\"mediabox alignnone wp-image-4251\" height=\"204\" src=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/CIVA-Validation-UT-CoinOT8-6.jpg\" width=\"188\"><\/a><\/p>\n<\/p>\n<p class=\"titre-paragraphe\">\u00a0<\/p>\n<\/p>\n<p class=\"titre-paragraphe\">Avec le capteur de \u00d86,35 \u00a0mm fonctionnant \u00e0 2,25 MHz, le champ r\u00e9fract\u00e9 dans la pi\u00e8ce est plus divergent. Le profil du champ en fond de pi\u00e8ce entre les lignes \u00e0 -6 dB comprend des rayons g\u00e9om\u00e9triques orient\u00e9s entre 36\u00b0 et 55\u00b0. Mais comme le faisceau est divergent, on peut observer les rayons incidents critiques de faible amplitude (33\u00b0 sur le fond et 57\u00b0 sur une entaille verticale) tr\u00e8s proches de cette partie du faisceau \u00e0 -6 dB.<\/p>\n<\/p>\n<p class=\"titre-paragraphe\">\u00a0<\/p>\n<\/p>\n<p class=\"titre-paragraphe\" style=\"text-align: center;\"><a class=\"mediabox\" href=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/CIVA-Validation-UT-CoinOT8-7.jpg\" style=\"text-decoration: none;\" title=\"\"><img loading=\"lazy\" decoding=\"async\" align=\"\" alt=\"\" class=\"mediabox alignnone wp-image-4252\" height=\"260\" src=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/CIVA-Validation-UT-CoinOT8-7.jpg\" width=\"300\" srcset=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/CIVA-Validation-UT-CoinOT8-7.jpg 412w, https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/CIVA-Validation-UT-CoinOT8-7-300x259.jpg 300w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><a class=\"mediabox\" href=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/CIVA-Validation-UT-CoinOT8-7bis.jpg\" style=\"text-decoration: none;\" title=\"\"><img loading=\"lazy\" decoding=\"async\" align=\"\" alt=\"\" class=\"mediabox alignnone wp-image-4253\" height=\"260\" src=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/CIVA-Validation-UT-CoinOT8-7bis.jpg\" width=\"300\" srcset=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/CIVA-Validation-UT-CoinOT8-7bis.jpg 412w, https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/CIVA-Validation-UT-CoinOT8-7bis-300x259.jpg 300w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<\/p>\n<p class=\"titre-paragraphe\">\u00a0<\/p>\n<\/p>\n<p class=\"titre-paragraphe\">Lorsque le capteur de \u00d86,35 mm \u00e0 2,25 MHz se trouve sur certaines positions, quelques rayons incidents arrivent sur la surface de l\u2019entaille avec des angles critiques \u00e0 cause de la grande divergence du faisceau. Cela pourrait expliquer les \u00e9carts observ\u00e9s sur les courbes \u00e9chodynamiques exp\u00e9rimentales et simul\u00e9es. N\u00e9anmoins, ces contributions critiques sont tr\u00e8s faibles (les rayons critiques arrivant sur le fond ou sur l\u2019entaille appartiennent \u00e0 une partie du faisceau de faible amplitude) par rapport \u00e0 celle de l\u2019onde T de volume qui est doublement r\u00e9fl\u00e9chie (\u00e9cho de coin classique). C\u2019est d\u2019autant plus vrai pour les plus grands d\u00e9fauts. Pour les d\u00e9fauts de faible hauteur, l\u2019\u00e9cho de coin classique pr\u00e9sente une amplitude faible ; ainsi, l\u2019amplitude pr\u00e9dite par CIVA diminue de 11 \u00a0dB lorsque la hauteur de l\u2019entaille passe de 4 mm \u00e0 1 mm. Par cons\u00e9quent, la contribution relative des ondes rampantes et de t\u00eate peut avoir un effet plus important sur l\u2019\u00e9cho global. Cependant, pour cette inspection, les contributions li\u00e9es aux ph\u00e9nom\u00e8nes critiques restent faibles. Il est tr\u00e8s difficile de s\u00e9parer les effets li\u00e9s \u00e0 la mod\u00e9lisation du faisceau de ceux li\u00e9s aux contributions critiques. En fait, dans le cas des plus petites entailles, il a \u00e9t\u00e9 observ\u00e9 avec ce traducteur les effets combin\u00e9s de la fr\u00e9quence par rapport \u00e0 la hauteur de l\u2019entaille, de la mod\u00e9lisation du champ et des (faibles) contributions critiques. Ces trois effets ne sont pas dissociables.<br \/>\nSi les contributions associ\u00e9es aux ph\u00e9nom\u00e8nes critiques sont tr\u00e8s faibles dans le cas des \u00e9chos de coin T45, leur contribution est beaucoup plus importante pour les inspections T55, T60 et T65 parce que les rayons critiques sont g\u00e9n\u00e9r\u00e9s \u00e0 partir de rayons incidents de plus grande amplitude (autour de l\u2019axe du traducteur).<\/p>\n<\/p>\n<p class=\"titre-paragraphe\">\u00a0<\/p>\n<\/p>\n<p class=\"titre-paragraphe\">Nous rappelons que ces ph\u00e9nom\u00e8nes sont susceptibles de g\u00e9n\u00e9rer deux effets diff\u00e9rents :<\/p>\n<\/p>\n<p class=\"titre-paragraphe\">\u00a0<\/p>\n<\/p>\n<p class=\"titre-paragraphe\">\u00a0<\/p>\n<\/p>\n<ul class=\"liste-carres-noirs\">\n<li>\n<div class=\"titre-paragraphe\">La g\u00e9n\u00e9ration d\u2019ondes rasantes et de t\u00eate pour des angles d\u2019incidence critiques sur l\u2019entaille ou sur le fond de la pi\u00e8ce. Ces ondes contribuent de mani\u00e8re suppl\u00e9mentaire \u00e0 l\u2019\u00e9cho de coin et certaines de ces contributions ne sont pas mod\u00e9lis\u00e9es par CIVA 10. <strong>(Mise \u00e0 jour : elles ne sont toujours pas simul\u00e9es dans CIVA 2021 avec le mod\u00e8le dl&rsquo;approximation d&rsquo;onde plane et le mod\u00e8le Full beam (Champ Complet) pour l&rsquo;interfaction champ\/d\u00e9faut mais elles sont prises en compte dans le mod\u00e8le TFEM disponible depuis CIVA 2020)<\/strong>. Ces contributions d\u00e9pendent fortement de la taille de l\u2019entaille et de la fr\u00e9quence. Les ph\u00e9nom\u00e8nes li\u00e9s \u00e0 ces ondes rasantes et de t\u00eate ont une forte incidence sur l\u2019amplitude des \u00e9chos de coin des entailles en particulier de petite hauteur.<\/div>\n<\/li>\n<li>\n<div class=\"titre-paragraphe\">La variation tr\u00e8s rapide du coefficient de r\u00e9flexion en fonction de l\u2019angle d\u2019incidence qui, autour de l\u2019angle critique, affecte les ondes de volume r\u00e9fl\u00e9chies sur le fond de la pi\u00e8ce et sur l\u2019entaille. En effet, le module de ce coefficient est quasi nul en dessous de l\u2019angle critique et maximal au dessus. Ce coefficient gouverne la r\u00e9flectivit\u00e9 de l\u2019entaille (et donc l\u2019amplitude de l\u2019\u00e9cho de coin) qui d\u00e9pend fortement de l\u2019angle d\u2019incidence r\u00e9el sur l\u2019entaille (en particulier autour de l\u2019angle critique).\u00a0<\/div>\n<\/li>\n<\/ul>\n<p>\u00a0<\/p>\n<\/p>\n<div style=\"text-align: center;\"><a class=\"mediabox\" href=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/CIVA-Validation-UT-CoinOT8-8.png\" style=\"text-decoration: none;\" title=\"\"><img loading=\"lazy\" decoding=\"async\" align=\"\" alt=\"\" class=\"mediabox alignnone wp-image-4254\" height=\"150\" src=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/CIVA-Validation-UT-CoinOT8-8.png\" width=\"200\" srcset=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/CIVA-Validation-UT-CoinOT8-8.png 562w, https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/CIVA-Validation-UT-CoinOT8-8-300x225.png 300w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/a><\/div>\n<\/p>\n<p class=\"titre-paragraphe\">\u00a0<\/p>\n<\/p>\n<p class=\"titre-paragraphe\">Les variations de ce coefficient peuvent entra\u00eener des effets, m\u00eame pour des angles \u00e9loign\u00e9s de l\u2019angle critique (57\u00b0). Elles peuvent \u00eatre, par exemple, \u00e0 l\u2019origine d\u2019une division des \u00e9chos pour certains modes d\u2019inspection. CIVA ne consid\u00e9re qu\u2019une seule incidence moyenne sur chaque point de la surface de l\u2019entaille. Cette approximation est susceptible d\u2019\u00eatre trop restrictive compar\u00e9e \u00e0 une prise en compte de tous les rayons incidents arrivant sur ce point.<br \/>\nLa combinaison des deux effets pr\u00e9c\u00e9dents peut expliquer les diff\u00e9rences observ\u00e9es sur les courbes \u00e9chodynamiques exp\u00e9rimentales et simul\u00e9es notamment pour les traducteurs divergents. Ces effets peuvent apparaitre pour les angles de r\u00e9fraction T55, T60 \u00e0 proximit\u00e9 de l\u2019incidence critique sur l\u2019entaille (T57) mais aussi pour les angles T65.<br \/>\nComme les ph\u00e9nom\u00e8nes d\u2019interaction sont tr\u00e8s complexes et d\u00e9pendent de plusieurs param\u00e8tres (angle de r\u00e9fraction des ondes T, taille de l\u2019entaille, divergence du faisceau (c\u2019est-\u00e0-dire ouverture et fr\u00e9quence centrale du traducteur)), il n\u2019est pas possible, pour les angles T55\u00b0-T60\u00b0 proches de l\u2019angle critique, de donner des limites pr\u00e9cises du domaine de validit\u00e9 en termes de k.a par exemple. A T45\u00b0 les incidences critiques sont plus n\u00e9gligeables, ce qui permet de continuer \u00e0 raisonner sur les limites de k.a.<\/p>\n<\/p>\n<p>\u00a0<\/p>\n<\/p>\n<h2 class=\"titre-paragraphe\">Un d\u00e9calage et un d\u00e9doublement des \u00e9chos aux grands angles d&rsquo;incidence<\/h2>\n<\/p>\n<p><span style=\"line-height: 1.5em;\">Dans le cas d\u2019ondes T \u00e0 grande incidence, on remarque que, sur les r\u00e9sultats exp\u00e9rimentaux et de simulation, les \u00e9chos de coins sont d\u00e9cal\u00e9s de l\u2019extr\u00e9mit\u00e9 de l\u2019entaille, certains sont m\u00eame d\u00e9doubl\u00e9s.<\/span><\/p>\n<\/p>\n<p class=\"titre-paragraphe\">Les \u00e9chos de coin associ\u00e9s aux ondes de volume sont a priori pr\u00e9dominants en amplitude, les explications suivantes consid\u00e8rent qu\u2019aucune onde de surface ne se propage. L\u2019\u00e9cho de coin \u00e9tant (notamment pour les grandes entailles) essentiellement un ph\u00e9nom\u00e8ne sp\u00e9culaire d\u00fb aux r\u00e9flexions des ondes de volume sur l\u2019entaille et le fond de la pi\u00e8ce, les explications seront bas\u00e9es sur des consid\u00e9rations g\u00e9om\u00e9triques.<br \/>\nPour un faisceau \u00e0 45\u00b0, \u00e0 une position de balayage pour laquelle le faisceau des ondes T r\u00e9fract\u00e9es croise le bas de l\u2019entaille, le champ direct sur l\u2019entaille et le champ r\u00e9fl\u00e9chi sur le fond sont simultan\u00e9ment maximaux \u00e0 la base de l\u2019entaille. Comme l\u2019\u00e9cho de coin est th\u00e9oriquement proportionnel \u00e0 ces composantes directes et r\u00e9fl\u00e9chies sur le fond, cet \u00e9cho sera maximal \u00e0 la base de l\u2019entaille, l\u00e0 o\u00f9 l\u2019axe focal croise l\u2019entaille.<\/p>\n<\/p>\n<p class=\"titre-paragraphe\">Pour un faisceau \u00e0 60\u00b0 (figure ci-dessous), on peut voir que les angles de r\u00e9fraction des rayons contenus dans le faisceau varient, le long de la hauteur de l\u2019entaille, de 56\u00b0 (au bas de l\u2019entaille) \u00e0 63\u00b0 (\u00e0 son sommet). Ainsi, les angles d\u2019incidence correspondant sur la surface de l\u2019entaille varient entre environ 27\u00b0 et 34\u00b0. Ces angles sont pr\u00e8s de l\u2019angle critique (\u03b8 = 33\u00b0) et correspondent donc \u00e0 une zone de fortes fluctuations du coefficient de diffraction de Kirchhoff utilis\u00e9 pour la mod\u00e9lisation des \u00e9chos de coin.<\/p>\n<\/p>\n<p class=\"titre-paragraphe\">\u00a0<\/p>\n<\/p>\n<p class=\"titre-paragraphe\" style=\"text-align: center;\"><a class=\"mediabox\" href=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/CIVA-Validation-UT-CoinOT8-9.png\" style=\"text-decoration: none;\" title=\"\"><img loading=\"lazy\" decoding=\"async\" align=\"\" alt=\"\" class=\"mediabox alignnone wp-image-4255\" height=\"174\" src=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/CIVA-Validation-UT-CoinOT8-9.png\" width=\"600\" srcset=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/CIVA-Validation-UT-CoinOT8-9.png 910w, https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/CIVA-Validation-UT-CoinOT8-9-300x87.png 300w, https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/CIVA-Validation-UT-CoinOT8-9-768x223.png 768w, https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/CIVA-Validation-UT-CoinOT8-9-600x174.png 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<\/p>\n<p class=\"titre-paragraphe\" style=\"text-align: center;\"><a class=\"mediabox\" href=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/CIVA-Validation-UT-CoinOT8-8.png\" style=\"text-decoration: none;\" title=\"\"><img loading=\"lazy\" decoding=\"async\" align=\"\" alt=\"\" class=\"mediabox alignnone wp-image-4254\" height=\"150\" src=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/CIVA-Validation-UT-CoinOT8-8.png\" width=\"200\" srcset=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/CIVA-Validation-UT-CoinOT8-8.png 562w, https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/CIVA-Validation-UT-CoinOT8-8-300x225.png 300w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/a><\/p>\n<\/p>\n<p class=\"titre-paragraphe\">\u00a0<\/p>\n<\/p>\n<p class=\"titre-paragraphe\">Consid\u00e9rons, par exemple, les 2 positions du capteur, \u00ab a \u00bb et \u00ab b \u00bb, illustr\u00e9es ci-dessous.<\/p>\n<\/p>\n<p class=\"titre-paragraphe\">\u00a0<\/p>\n<\/p>\n<p class=\"titre-paragraphe\" style=\"text-align: center;\"><a class=\"mediabox\" href=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/CIVA-Validation-UT-CoinOT8-10.png\" style=\"text-decoration: none;\" title=\"\"><img loading=\"lazy\" decoding=\"async\" align=\"\" alt=\"\" class=\"mediabox alignnone wp-image-4256\" height=\"168\" src=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/CIVA-Validation-UT-CoinOT8-10.png\" width=\"400\" srcset=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/CIVA-Validation-UT-CoinOT8-10.png 656w, https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/CIVA-Validation-UT-CoinOT8-10-300x126.png 300w, https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/CIVA-Validation-UT-CoinOT8-10-600x252.png 600w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a><\/p>\n<\/p>\n<p class=\"titre-paragraphe\">\u00a0<\/p>\n<\/p>\n<p class=\"titre-paragraphe\">A la position \u00ab a \u00bb, le faisceau intercepte l\u2019entaille avec des incidences inf\u00e9rieures \u00e0 l\u2019incidence critique (rayons bleus sur la figure). Des conversions de modes se produident donc \u00e0 la surface de l\u2019entaille mais la contribution de cette partie du faisceau \u00e0 l\u2019\u00e9cho de coin T est faible (cf. valeur du coefficient de diffraction de Kirchhoff pour les angles d\u2019incidence inf\u00e9rieurs \u00e0 33\u00b0).<\/p>\n<\/p>\n<p class=\"titre-paragraphe\">En position \u00ab b \u00bb, le faisceau arrive sur l\u2019entaille avec des incidence sup\u00e9rieures \u00e0 l\u2019incidence critique (rayons verts). Pour de telles incidences, la r\u00e9flexion des ondes T sur l\u2019entaille est tr\u00e8s importante (cf. valeur du coefficient de diffraction de Kirchhoff pour les angles d\u2019incidence sup\u00e9rieurs \u00e0 33\u00b0) et en particulier plus importante que lorsque le rayon central du faisceau arrive \u00e0 la base du d\u00e9faut. Ainsi, pour le cas T60\u00b0, l\u2019amplitude maximale de l\u2019\u00e9cho de coin T est obtenue aux positions de balayage auxquelles l\u2019axe focal T intercepte le fond de la pi\u00e8ce \u00e0 droite du bas de l\u2019entaille (position \u00ab b \u00bb). La position o\u00f9 l\u2019on mesure la plus forte amplitude est donc d\u00e9cal\u00e9e par rapport \u00e0 l\u2019entaille.<\/p>\n<\/p>\n<p class=\"titre-paragraphe\">Les m\u00eames explications peuvent justifier la division de l\u2019\u00e9cho de coin en deux contributions. Ce ph\u00e9nom\u00e8ne est d\u00fb aux variations des angles d\u2019incidence des rayons contenus dans le faisceau r\u00e9fract\u00e9 (variations d\u00e9pendant des angles de r\u00e9fraction des ondes T) et \u00e0 leur effet sur l\u2019int\u00e9raction avec l\u2019entaille. Ce d\u00e9calage d\u2019\u00e9cho de coin en T60 est aussi reproduit par les mod\u00e8les de CIVA.<\/p>\n<\/p>\n<p class=\"titre-paragraphe\">Les B-scans exp\u00e9rimentaux suivants permettent de visualiser le d\u00e9calage et le d\u00e9doublement de la signature dans le cas d\u2019un capteur en immersion de \u00d812,7 mm \u00e0 2,25 MHz avec une hauteur d\u2019eau de 50 mm.<\/p>\n<\/p>\n<p class=\"titre-paragraphe\">\u00a0<\/p>\n<\/p>\n<p class=\"titre-paragraphe\" style=\"text-align: center;\"><a class=\"mediabox\" href=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/CIVA-Validation-UT-CoinOT8-11.png\" style=\"text-decoration: none;\" title=\"\"><img loading=\"lazy\" decoding=\"async\" align=\"\" alt=\"\" class=\"mediabox alignnone wp-image-4257\" height=\"210\" src=\"https:\/\/extende.realisateurweb.com\/wp-content\/uploads\/CIVA-Validation-UT-CoinOT8-11.png\" width=\"400\"><\/a><\/p>\n<\/p>\n<p>\u00a0<\/p>\n<\/p>\n<p>\u00a0<\/p>\n<\/p>\n<p>Retourner au menu <a class=\"lien\" href=\"https:\/\/extende.realisateurweb.com\/fr\/la-simulation-cnd\/documentation\/validation-experimentale-des-modeles-civa\/validation-experimentale-des-modeles-civa-en-ultrasons\/ultrasons-echos-de-coin\/echos-de-coin-en-ondes-t\/\" target=\"_self\">Echos de coin en ondes T<\/a><\/p>\n<\/p>\n<p>Retourner au menu <a class=\"lien\" href=\"https:\/\/extende.realisateurweb.com\/fr\/la-simulation-cnd\/documentation\/validation-experimentale-des-modeles-civa\/validation-experimentale-des-modeles-civa-en-ultrasons\/ultrasons-echos-de-coin\/\" target=\"_self\">Echos de coin<\/a><\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Validation exp\u00e9rimentale et caract\u00e9risation des mod\u00e8les Ultrasons de CIVA, \u00e9chos de coin, logiciel de simulation CND<\/p>\n","protected":false},"author":0,"featured_media":0,"parent":2942,"menu_order":8,"comment_status":"closed","ping_status":"closed","template":"templates\/page--extende.html.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-4258","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/extende.realisateurweb.com\/fr\/wp-json\/wp\/v2\/pages\/4258","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/extende.realisateurweb.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/extende.realisateurweb.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"replies":[{"embeddable":true,"href":"https:\/\/extende.realisateurweb.com\/fr\/wp-json\/wp\/v2\/comments?post=4258"}],"version-history":[{"count":1,"href":"https:\/\/extende.realisateurweb.com\/fr\/wp-json\/wp\/v2\/pages\/4258\/revisions"}],"predecessor-version":[{"id":5572,"href":"https:\/\/extende.realisateurweb.com\/fr\/wp-json\/wp\/v2\/pages\/4258\/revisions\/5572"}],"up":[{"embeddable":true,"href":"https:\/\/extende.realisateurweb.com\/fr\/wp-json\/wp\/v2\/pages\/2942"}],"wp:attachment":[{"href":"https:\/\/extende.realisateurweb.com\/fr\/wp-json\/wp\/v2\/media?parent=4258"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}